{"id":29232,"date":"2026-07-14T00:00:00","date_gmt":"2026-07-14T00:00:00","guid":{"rendered":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/"},"modified":"2026-07-14T00:00:00","modified_gmt":"2026-07-14T00:00:00","slug":"334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia","status":"publish","type":"post","link":"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/","title":{"rendered":"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia"},"content":{"rendered":"<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA SLB (NYSE: SLB), empresa global de tecnologia energ\u00e9tica, anunciou hoje um acordo com a Liberty Energy Inc. (NYSE: LBRT) para formar uma alian\u00e7a estrat\u00e9gica que fornecer\u00e1 infraestrutura modular e solu\u00e7\u00f5es integradas de gera\u00e7\u00e3o de energia para novos projetos de data centers em todo o mundo.<\/p>\n<p id=\"news-body-cta\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">Este comunicado de imprensa inclui multim\u00e9dia. Veja o comunicado completo aqui: <a href=\"https:\/\/www.businesswire.com\/news\/home\/20260714984102\/pt\/\" rel=\"follow\" target=\"_blank\">https:\/\/www.businesswire.com\/news\/home\/20260714984102\/pt\/<\/a><\/p>\n<div id=\"bwbodyimg\" style=\"width: 480px; float:left; padding-left:0px; padding-right:20px; padding-top:0px; padding-bottom:0px;\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><img decoding=\"async\" src=\"https:\/\/mms.businesswire.com\/media\/20260714984102\/pt\/2850858\/4\/Datacenter-A-Still_5.jpg\" alt=\"A rendering of modular data center infrastructure with co-located, behind-the-meter generation.\"><\/p>\n<p style=\"font-size:85%;\">A rendering of modular data center infrastructure with co-located, behind-the-meter generation.<\/p>\n<\/div>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA colabora\u00e7\u00e3o reunir\u00e1 conhecimentos complementares em infraestrutura modular, gera\u00e7\u00e3o de energia e opera\u00e7\u00f5es para apoiar a r\u00e1pida implanta\u00e7\u00e3o de nova capacidade de data center e ajudar as principais empresas de IA do mundo a atender \u00e0s necessidades energ\u00e9ticas cada vez mais complexas.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nO crescimento da IA \u200b\u200be da computa\u00e7\u00e3o de alto desempenho est\u00e1 impulsionando uma demanda sem precedentes por capacidade de data center. \u00c0 medida que os desenvolvedores trabalham para adicionar nova capacidade computacional, muitos buscam solu\u00e7\u00f5es de energia &#8220;atr\u00e1s do medidor&#8221; que possam ser implantadas independentemente das conex\u00f5es tradicionais &agrave; rede el\u00e9trica, ao mesmo tempo que melhoram a confiabilidade, a efici\u00eancia e a flexibilidade conforme as necessidades de energia aumentam.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n&#8220;O gargalo na infraestrutura de IA n\u00e3o \u00e9 mais apenas a computa\u00e7\u00e3o. \u00c9 a capacidade de fornecer infraestrutura e energia nos prazos que o mercado exige atualmente&#8221;, disse Gavin Rennick, presidente da Divis\u00e3o de Novas Energias e Ind\u00fastria da SLB. &#8220;Ao reunir capacidades complementares de infraestrutura e energia, ajudaremos os desenvolvedores a acelerar a implanta\u00e7\u00e3o de nova capacidade de data center.&#8221;<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nSob a alian\u00e7a planejada, a SLB fornecer\u00e1 solu\u00e7\u00f5es de infraestrutura modular, capacidade de execu\u00e7\u00e3o de projetos e alcance de mercado global, enquanto a Liberty fornecer\u00e1 sistemas modulares de gera\u00e7\u00e3o de energia, controles inteligentes de energia instalados no ponto de venda e expertise operacional.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n\u201cA escala e a complexidade da infraestrutura de energia com intelig\u00eancia artificial est\u00e3o mudando fundamentalmente a forma como os sistemas de energia s\u00e3o constru\u00eddos e implantados\u201d, disse Ron Gusek, CEO da Liberty Energy. \u201cA plataforma abrangente de servi\u00e7os de energia da Liberty foi projetada para atender a essa transi\u00e7\u00e3o, &agrave; medida que os clientes priorizam cada vez mais solu\u00e7\u00f5es integradas e personalizadas. Com base em nosso relacionamento de longa data com a SLB, estamos entusiasmados em trazer solu\u00e7\u00f5es de energia que atendam \u00e0s restri\u00e7\u00f5es de capacidade imediatas, ao mesmo tempo que apoiam a pr\u00f3xima gera\u00e7\u00e3o de sistemas de energia.\u201d<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nAl\u00e9m de fornecer solu\u00e7\u00f5es de infraestrutura e energia, as empresas planejam colaborar em tecnologias voltadas para a melhoria da efici\u00eancia, flexibilidade e desempenho ambiental dos futuros sistemas de energia de data centers, incluindo sistemas de energia h\u00edbridos, gerenciamento digital de energia e arquiteturas de energia avan\u00e7adas.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nDesde abril de 2024, a SLB j\u00e1 entregou mais de 1,3 gigawatts de infraestrutura modular pr\u00e9-fabricada para projetos de data centers e espera que as entregas cumulativas ultrapassem 2 gigawatts globalmente at\u00e9 o final do ano. A Liberty planeja implantar aproximadamente 3 gigawatts em projetos de energia at\u00e9 2029.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Pontos-chave:<\/b><\/p>\n<ul class=\"bwlistdisc\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n<li>\nA SLB e a Liberty Energy anunciaram um acordo para formar uma alian\u00e7a estrat\u00e9gica para fornecer solu\u00e7\u00f5es de infraestrutura modular e gera\u00e7\u00e3o de energia integrada para projetos de data centers em todo o mundo.<\/p>\n<\/li>\n<li>\nA alian\u00e7a planejada combinar\u00e1 as solu\u00e7\u00f5es de infraestrutura modular para data centers e a experi\u00eancia em execu\u00e7\u00e3o de projetos da SLB com a gera\u00e7\u00e3o de energia modular e os recursos de gerenciamento inteligente de energia &#8220;behind-the-meter&#8221; da Liberty, para atender &agrave; crescente demanda por infraestrutura de IA e computa\u00e7\u00e3o de alto desempenho.<\/p>\n<\/li>\n<li>\n\u00c0 medida que os desenvolvedores buscam disponibilizar nova capacidade computacional online, a alian\u00e7a planejada visa atender &agrave; crescente demanda por solu\u00e7\u00f5es de energia &#8220;behind-the-meter&#8221; que possam ser implantadas independentemente dos prazos tradicionais de conex\u00e3o &agrave; rede el\u00e9trica.<\/p>\n<\/li>\n<li>\nAs empresas tamb\u00e9m planejam colaborar em futuras iniciativas tecnol\u00f3gicas focadas em sistemas de energia h\u00edbridos, gerenciamento digital de energia e arquiteturas de energia avan\u00e7adas para atender aos requisitos de energia em constante evolu\u00e7\u00e3o dos data centers.<\/p>\n<\/li>\n<\/ul>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Sobre a SLB<\/b><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA SLB (NYSE: SLB) \u00e9 uma empresa global de tecnologia que impulsiona a inova\u00e7\u00e3o energ\u00e9tica h\u00e1 100 anos. Com presen\u00e7a global em mais de 100 pa\u00edses e funcion\u00e1rios representando quase o dobro de nacionalidades, trabalhamos diariamente para inovar no setor de petr\u00f3leo e g\u00e1s, fornecer solu\u00e7\u00f5es digitais em larga escala, descarbonizar ind\u00fastrias e desenvolver e expandir novos sistemas de energia que aceleram a transi\u00e7\u00e3o energ\u00e9tica. Saiba mais em <a href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fwww.slb.com&amp;esheet=54569932&amp;newsitemid=20260714984102&amp;lan=pt-BR&amp;anchor=slb.com&amp;index=1&amp;md5=b44d81aec506b34c86e6561aca3ec950\" rel=\"follow\" shape=\"rect\" target=\"_blank\">slb.com<\/a>.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Sobre a Liberty Energy<\/b><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nLiberty Energy Inc. (NYSE: LBRT) \u00e9 uma empresa l\u00edder em servi\u00e7os de energia. A Liberty \u00e9 uma das maiores fornecedoras de servi\u00e7os e tecnologias de completa\u00e7\u00e3o para produtores onshore de petr\u00f3leo, g\u00e1s natural e energia geot\u00e9rmica aprimorada na Am\u00e9rica do Norte. A Liberty tamb\u00e9m possui e opera a Liberty Power Innovations LLC, fornecendo solu\u00e7\u00f5es avan\u00e7adas de energia distribu\u00edda e armazenamento de energia, apoiadas por relacionamentos estrat\u00e9gicos em sistemas avan\u00e7ados de armazenamento de energia nuclear, geot\u00e9rmica aprimorada e de bateria, atendendo aos setores comercial e industrial, de data center, de energia e de minera\u00e7\u00e3o. A Liberty foi fundada em 2011 com um foco incans\u00e1vel na cria\u00e7\u00e3o de valor atrav\u00e9s de uma cultura de inova\u00e7\u00e3o e excel\u00eancia e no desenvolvimento de tecnologia de pr\u00f3xima gera\u00e7\u00e3o. A Liberty est\u00e1 sediada em Denver, Colorado. Para obter mais informa\u00e7\u00f5es, acesse <a href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=http%3A%2F%2Fwww.libertyenergy.com&amp;esheet=54569932&amp;newsitemid=20260714984102&amp;lan=pt-BR&amp;anchor=www.libertyenergy.com&amp;index=2&amp;md5=caf23d9243264bc51de7af2c5da51b52\" rel=\"follow\" shape=\"rect\" target=\"_blank\">www.libertyenergy.com<\/a> e <a href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Flibertyenergy.com%2Fpower-generation-and-fueling%2Fliberty-power-innovations%2F&amp;esheet=54569932&amp;newsitemid=20260714984102&amp;lan=pt-BR&amp;anchor=libertypowerinnovations.com&amp;index=3&amp;md5=b015ffc77d662377aa53e5d47b8a8c65\" rel=\"follow\" shape=\"rect\" target=\"_blank\">libertypowerinnovations.com<\/a>, ou entre em contato com Rela\u00e7\u00f5es com Investidores em <a href=\"mailto:IR@libertyenergy.com\" rel=\"follow\" shape=\"rect\" target=\"_blank\">IR@libertyenergy.com<\/a>.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Declara\u00e7\u00e3o de advert\u00eancia sobre declara\u00e7\u00f5es prospectivas:<\/b><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nEste comunicado &agrave; imprensa cont\u00e9m \u201cdeclara\u00e7\u00f5es prospectivas\u201d de acordo com o significado das leis federais de valores mobili\u00e1rios dos EUA \u2013 ou seja, declara\u00e7\u00f5es sobre o futuro, n\u00e3o sobre eventos passados. Tais declara\u00e7\u00f5es geralmente cont\u00eam palavras como \u201cplanejar\u201d, \u200b\u200b\u201cesperar\u201d, \u201cpoder\u201d, \u201cestimar\u201d, \u201cpretender\u201d, \u201cantecipar\u201d, \u201cir\u00e1\u201d, \u201cpotencial\u201d, \u201cprojetado\u201d e outras palavras semelhantes. As declara\u00e7\u00f5es prospectivas abordam assuntos que s\u00e3o, em v\u00e1rios graus, incertos, como previs\u00f5es ou expectativas em rela\u00e7\u00e3o &agrave; implanta\u00e7\u00e3o ou benef\u00edcios previstos das novas tecnologias, alian\u00e7as e parcerias do SLB ou da Liberty; previs\u00f5es ou expectativas relativas &agrave; demanda por capacidade de data center; e melhorias nos procedimentos operacionais e na tecnologia. Estas declara\u00e7\u00f5es est\u00e3o sujeitas a riscos e incertezas, incluindo, mas n\u00e3o se limitando a, a incapacidade de reconhecer os benef\u00edcios pretendidos das estrat\u00e9gias, iniciativas ou parcerias do SLB ou da Liberty; e outros riscos e incertezas detalhados nos Formul\u00e1rios 10-K, 10-Q e 8-K mais recentes do SLB ou da Liberty arquivados ou fornecidos &agrave; Comiss\u00e3o de Valores Mobili\u00e1rios dos EUA. Se um ou mais destes ou outros riscos ou incertezas se materializarem (ou as consequ\u00eancias de tal desenvolvimento mudarem), ou se as suposi\u00e7\u00f5es subjacentes se revelarem incorretas, os resultados reais poder\u00e3o variar materialmente daqueles refletidos nas nossas declara\u00e7\u00f5es prospectivas. As declara\u00e7\u00f5es prospectivas s\u00e3o v\u00e1lidas apenas na data deste comunicado &agrave; imprensa, e a SLB e a Liberty se isentam de qualquer inten\u00e7\u00e3o ou obriga\u00e7\u00e3o de atualizar publicamente ou revisar tais declara\u00e7\u00f5es, seja como resultado de novas informa\u00e7\u00f5es, eventos futuros ou de outra forma.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nO texto no idioma original deste an\u00fancio \u00e9 a vers\u00e3o oficial autorizada. As tradu\u00e7\u00f5es s\u00e3o fornecidas apenas como uma facilidade e devem se referir ao texto no idioma original, que \u00e9 a \u00fanica vers\u00e3o do texto que tem efeito legal.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260714984102r1&amp;sid=brdno&amp;distro=ftp\"><span class=\"bwct31415\"><\/span><\/p>\n<p id=\"mmgallerylink\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><span id=\"mmgallerylink-phrase\">Ver a vers\u00e3o original em businesswire.com: <\/span><span id=\"mmgallerylink-link\"><a href=\"https:\/\/www.businesswire.com\/news\/home\/20260714984102\/pt\/\" rel=\"follow\" target=\"_blank\">https:\/\/www.businesswire.com\/news\/home\/20260714984102\/pt\/<\/a><\/span><\/p>\n<p><b>Contato:<\/b><\/p>\n<p><b>Imprensa\n<\/p>\n<p><\/b>Josh Byerly \u2013 Vice-Presidente S\u00eanior de Comunica\u00e7\u00f5es Globais\n<\/p>\n<p>Moira Duff \u2013 Diretora de Comunica\u00e7\u00f5es Externas\n<\/p>\n<p>SLB\n<\/p>\n<p>Tel: +1 (713) 375-3407\n<\/p>\n<p><a href=\"mailto:media@slb.com\" rel=\"follow\" shape=\"rect\">media@slb.com<\/a><\/p>\n<p><b>Investidores\n<\/p>\n<p><\/b>James R. McDonald \u2013 Vice-Presidente S\u00eanior de Rela\u00e7\u00f5es com Investidores e Assuntos do Setor\n<\/p>\n<p>Joy V. Domingo \u2013 Diretora de Rela\u00e7\u00f5es com Investidores\n<\/p>\n<p>SLB\n<\/p>\n<p>Tel: +1 (713) 375-3535\n<\/p>\n<p><a href=\"mailto:investor-relations@slb.com\" rel=\"follow\" shape=\"rect\">investor-relations@slb.com<\/a><\/p>\n<p>\nMichael Stock \u2013 Diretor Financeiro\n<\/p>\n<p>Anjali Voria, CFA \u2013 Vice-Presidente de Rela\u00e7\u00f5es com Investidores\n<\/p>\n<p>Liberty Energy\n<\/p>\n<p>Tel: +1 (303) 515-2851\n<\/p>\n<p><a href=\"mailto:IR@libertyenergy.com\" rel=\"follow\" shape=\"rect\">IR@libertyenergy.com<\/a><\/p>\n<p><strong>Fonte: <\/strong><a href='http:\/\/www.businesswire.com\/portal\/site\/home\/' target='_blank'>BUSINESS WIRE<\/a><img src='https:\/\/api.dino.com.br\/v2\/news\/tr\/334016?partnerId=4593' alt=\"\" style=\"border:0px;width:1px;height:1px;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>A alian\u00e7a planejada combina infraestrutura modular e solu\u00e7\u00f5es de energia integradas, projetadas para acelerar a expans\u00e3o global de data centers Implanta\u00e7\u00e3o<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[315],"tags":[349,331,347,339,324,369,323],"class_list":["post-29232","post","type-post","status-publish","format-standard","category-noticias-corporativas-dino","tag-arte","tag-engenharia","tag-industrias","tag-meio-ambiente","tag-negocios","tag-politicas","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"og:description\" content=\"A alian\u00e7a planejada combina infraestrutura modular e solu\u00e7\u00f5es de energia integradas, projetadas para acelerar a expans\u00e3o global de data centers Implanta\u00e7\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mms.businesswire.com\/media\/20260714984102\/pt\/2850858\/4\/Datacenter-A-Still_5.jpg\" \/>\n<meta name=\"author\" content=\"DINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/\"},\"author\":{\"name\":\"DINO\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\"},\"headline\":\"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia\",\"datePublished\":\"2026-07-14T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/\"},\"wordCount\":1398,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mms.businesswire.com\\\/media\\\/20260714984102\\\/pt\\\/2850858\\\/4\\\/Datacenter-A-Still_5.jpg\",\"keywords\":[\"ARTE\",\"ENGENHARIA\",\"IND\u00daSTRIAS\",\"MEIO AMBIENTE\",\"NEG\u00d3CIOS\",\"POL\u00cdTICAS\",\"TECNOLOGIA\"],\"articleSection\":[\"Not\u00edcias Corporativas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/\",\"name\":\"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mms.businesswire.com\\\/media\\\/20260714984102\\\/pt\\\/2850858\\\/4\\\/Datacenter-A-Still_5.jpg\",\"datePublished\":\"2026-07-14T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mms.businesswire.com\\\/media\\\/20260714984102\\\/pt\\\/2850858\\\/4\\\/Datacenter-A-Still_5.jpg\",\"contentUrl\":\"https:\\\/\\\/mms.businesswire.com\\\/media\\\/20260714984102\\\/pt\\\/2850858\\\/4\\\/Datacenter-A-Still_5.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/angelboss.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss\",\"description\":\"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil\",\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"alternateName\":\"Maior Portal e Blog de Beleza Masculina e Luxo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angelboss.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"width\":1280,\"height\":1280,\"caption\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\",\"name\":\"DINO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"caption\":\"DINO\"},\"url\":\"https:\\\/\\\/angelboss.com.br\\\/en\\\/author\\\/DINO\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/","og_locale":"en_US","og_type":"article","og_title":"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","og_description":"A alian\u00e7a planejada combina infraestrutura modular e solu\u00e7\u00f5es de energia integradas, projetadas para acelerar a expans\u00e3o global de data centers Implanta\u00e7\u00e3o","og_url":"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/","og_site_name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","article_published_time":"2026-07-14T00:00:00+00:00","og_image":[{"url":"https:\/\/mms.businesswire.com\/media\/20260714984102\/pt\/2850858\/4\/Datacenter-A-Still_5.jpg","type":"","width":"","height":""}],"author":"DINO","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DINO","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/#article","isPartOf":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/"},"author":{"name":"DINO","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5"},"headline":"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia","datePublished":"2026-07-14T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/"},"wordCount":1398,"commentCount":0,"publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"image":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/#primaryimage"},"thumbnailUrl":"https:\/\/mms.businesswire.com\/media\/20260714984102\/pt\/2850858\/4\/Datacenter-A-Still_5.jpg","keywords":["ARTE","ENGENHARIA","IND\u00daSTRIAS","MEIO AMBIENTE","NEG\u00d3CIOS","POL\u00cdTICAS","TECNOLOGIA"],"articleSection":["Not\u00edcias Corporativas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/","url":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/","name":"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","isPartOf":{"@id":"https:\/\/angelboss.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/#primaryimage"},"image":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/#primaryimage"},"thumbnailUrl":"https:\/\/mms.businesswire.com\/media\/20260714984102\/pt\/2850858\/4\/Datacenter-A-Still_5.jpg","datePublished":"2026-07-14T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/#primaryimage","url":"https:\/\/mms.businesswire.com\/media\/20260714984102\/pt\/2850858\/4\/Datacenter-A-Still_5.jpg","contentUrl":"https:\/\/mms.businesswire.com\/media\/20260714984102\/pt\/2850858\/4\/Datacenter-A-Still_5.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334016-slb-e-liberty-energy-formam-alianca-estrategica-para-infraestrutura-de-data-center-e-energia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/angelboss.com.br\/"},{"@type":"ListItem","position":2,"name":"SLB e Liberty Energy formam alian\u00e7a estrat\u00e9gica para infraestrutura de data center e energia"}]},{"@type":"WebSite","@id":"https:\/\/angelboss.com.br\/#website","url":"https:\/\/angelboss.com.br\/","name":"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss","description":"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil","publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"alternateName":"Maior Portal e Blog de Beleza Masculina e Luxo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angelboss.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/angelboss.com.br\/#organization","name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","url":"https:\/\/angelboss.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","contentUrl":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","width":1280,"height":1280,"caption":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss"},"image":{"@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5","name":"DINO","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","caption":"DINO"},"url":"https:\/\/angelboss.com.br\/en\/author\/DINO\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/29232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/comments?post=29232"}],"version-history":[{"count":0,"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/29232\/revisions"}],"wp:attachment":[{"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/media?parent=29232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/categories?post=29232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/tags?post=29232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}