{"id":34845,"date":"2026-09-01T00:00:00","date_gmt":"2026-09-01T00:00:00","guid":{"rendered":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/"},"modified":"2026-09-01T00:00:00","modified_gmt":"2026-09-01T00:00:00","slug":"336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita","status":"publish","type":"post","link":"http:\/\/angelboss.com.br\/en\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/","title":{"rendered":"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1]"},"content":{"rendered":"<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA ITC Infotech (ITCI), subsidi\u00e1ria integral da ITC Limited e l\u00edder global em servi\u00e7os de tecnologia, anunciou hoje a proposta de combina\u00e7\u00e3o estrat\u00e9gica com a Happiest Minds Technologies Limited (Happiest Minds) para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA. O Conselho da ITCI aprovou uma proposta para adquirir uma participa\u00e7\u00e3o acion\u00e1ria de 22,1% do acionista controlador da Happiest Minds em duas parcelas, por meio de um Contrato de Compra e Venda de A\u00e7\u00f5es. A transa\u00e7\u00e3o ser\u00e1 financiada por meio de uma Oferta de Direitos de Subscri\u00e7\u00e3o pela ITC Infotech. O Conselho da ITCI tamb\u00e9m aprovou uma proposta de Fus\u00e3o da Happiest Minds com a ITCI, que ser\u00e1 efetivada ap\u00f3s a aquisi\u00e7\u00e3o das a\u00e7\u00f5es. De acordo com o plano, as a\u00e7\u00f5es da ITCI ser\u00e3o negociadas em bolsa. A transa\u00e7\u00e3o proposta tamb\u00e9m foi aprovada pelo Conselho de Administra\u00e7\u00e3o da ITC Limited.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nEssa combina\u00e7\u00e3o estrat\u00e9gica integrar\u00e1 sinergicamente as capacidades da ITCI em IA nas \u00e1reas de Nuvem, An\u00e1lise de Dados, PLM, SAP, transforma\u00e7\u00e3o empresarial, solu\u00e7\u00f5es tecnol\u00f3gicas espec\u00edficas para cada setor e servi\u00e7os gerenciados completos, com os pontos fortes da Happiest Minds em Engenharia de Produtos Digitais orientada &agrave; constru\u00e7\u00e3o, Dados, Seguran\u00e7a Cibern\u00e9tica e expertise especializada em IA. A fus\u00e3o proposta resultar\u00e1 em uma mudan\u00e7a radical de escala para a ITCI, aumentando sua competitividade para conquistar grandes projetos de transforma\u00e7\u00e3o e ampliar sua capacidade em \u00e1reas cr\u00edticas para atender com efic\u00e1cia sua base de clientes e explorar novas oportunidades de valor que est\u00e3o surgindo com a r\u00e1pida ado\u00e7\u00e3o de IA nas empresas. A entidade resultante da fus\u00e3o tamb\u00e9m levar\u00e1 a uma presen\u00e7a substancialmente maior nos mercados dos EUA, bem como nos setores de Bancos, Servi\u00e7os Financeiros e Seguros. Al\u00e9m disso, segmentos-chave da ind\u00fastria, como Sa\u00fade, Alta Tecnologia e EdTech, tamb\u00e9m ser\u00e3o adicionados ao portf\u00f3lio da ITCI. Ao incorporar clientes de renome &agrave; base de clientes da ITCI, a fus\u00e3o proposta tamb\u00e9m desbloquear\u00e1 oportunidades significativas de vendas cruzadas e vendas adicionais.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nCom uma for\u00e7a de trabalho global combinada de mais de 19.000 profissionais, a empresa tamb\u00e9m aprofundar\u00e1 as capacidades complementares para oferecer uma proposta de valor completa para solu\u00e7\u00f5es de ponta a ponta, abrangendo Constru\u00e7\u00e3o, Intelig\u00eancia e Opera\u00e7\u00f5es, enquanto se expande para verticais de alto potencial, incluindo Alta Tecnologia, Sa\u00fade e EdTech.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Sanjiv Puri, presidente do Conselho da ITC Limited e da ITC Infotech,<\/b> disse: <i>&#8220;Hoje marca um importante passo na jornada para que a Happiest Minds se torne parte integrante da ITC Infotech, sujeita &agrave; obten\u00e7\u00e3o das aprova\u00e7\u00f5es regulat\u00f3rias. A uni\u00e3o de nossas for\u00e7as complementares, profundo conhecimento do setor e capacidades voltadas para o futuro fortalecer\u00e1 ainda mais nossa capacidade de fornecer solu\u00e7\u00f5es de ponta em diversas regi\u00f5es. Estou particularmente entusiasmado com os valores compartilhados, as pessoas e o foco no cliente que definem nossas organiza\u00e7\u00f5es. Aguardamos com expectativa a valiosa experi\u00eancia, conhecimento e dedica\u00e7\u00e3o dos funcion\u00e1rios da Happiest Minds ao embarcarmos neste novo e empolgante cap\u00edtulo.&#8221;<\/i><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Ashok Soota, presidente e mentor principal da Happiest Minds Technologies,<\/b> disse: \u201c<i>Estou muito satisfeito que, ap\u00f3s a conclus\u00e3o das formalidades legais, a Happiest Minds se tornar\u00e1 uma parte importante de uma organiza\u00e7\u00e3o maior por meio de sua fus\u00e3o com a ITC Infotech. As duas organiza\u00e7\u00f5es compartilham os mesmos valores e vis\u00e3o de futuro. H\u00e1 uma complementaridade muito significativa em nossos portf\u00f3lios de neg\u00f3cios, o que garantir\u00e1 sinergia. Acreditamos que a ITC Infotech \u00e9 a melhor parceira para a Happiest Minds alcan\u00e7ar seu potencial m\u00e1ximo e estamos felizes que nossa equipe encontrar\u00e1 um novo lar acolhedor<\/i>.\u201d<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Manas Chakraborty, diretor executivo da ITC Infotech, destacou que<\/b><i>\u201cEssa combina\u00e7\u00e3o visa fundamentalmente elevar o valor que entregamos aos nossos clientes. Integrar as capacidades de Engenharia Digital, Dados, IA e Seguran\u00e7a Cibern\u00e9tica da Happiest Minds com nossa profunda expertise no setor, nuvem e engenharia nos permitir\u00e1 atuar como um parceiro de transforma\u00e7\u00e3o completo, impulsionado por IA.\u201d<\/i><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA transa\u00e7\u00e3o proposta est\u00e1 sujeita &agrave; obten\u00e7\u00e3o das aprova\u00e7\u00f5es legais, dos acionistas e regulat\u00f3rias habituais, incluindo as aprova\u00e7\u00f5es da Comiss\u00e3o de Concorr\u00eancia da \u00cdndia, das bolsas de valores relevantes e do Tribunal Nacional de Direito Societ\u00e1rio. As empresas esperam que a transa\u00e7\u00e3o seja conclu\u00edda nos pr\u00f3ximos 15 meses e continuar\u00e3o a operar de forma independente at\u00e9 que todas as aprova\u00e7\u00f5es sejam obtidas. As a\u00e7\u00f5es da ITC Infotech ser\u00e3o negociadas nas bolsas de valores ap\u00f3s o recebimento de todas as aprova\u00e7\u00f5es.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Sobre a ITC Infotech:<\/b><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA ITC Infotech \u00e9 uma provedora l\u00edder global de servi\u00e7os e solu\u00e7\u00f5es de tecnologia, com foco em Consultoria de Neg\u00f3cios e Tecnologia. A ITC Infotech oferece solu\u00e7\u00f5es pr\u00e1ticas para ajudar os clientes a alcan\u00e7ar o sucesso e estarem preparados para o futuro, integrando expertise digital, fortes alian\u00e7as espec\u00edficas do setor e a capacidade \u00fanica de aproveitar o profundo conhecimento do dom\u00ednio das empresas do Grupo ITC. A empresa fornece solu\u00e7\u00f5es e servi\u00e7os de tecnologia para empresas em diversos setores, como Bancos e Servi\u00e7os Financeiros, Sa\u00fade, Manufatura, Bens de Consumo, Viagens e Hotelaria, por meio de uma combina\u00e7\u00e3o de modelos de neg\u00f3cios tradicionais e inovadores, como uma parceira sustent\u00e1vel de longo prazo.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nPara mais informa\u00e7\u00f5es, acesse: <a href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fprotect.checkpoint.com%2Fv2%2Fr05%2F___https%3A%2Fwww.itcinfotech.com%2F___.YXBzMTppdGNjb3JwOmM6b2ZmaWNlMzY1X2VtYWlsc19hdHRhY2htZW50OmE1ZWExNWYyZGE1YzM5OTE2YzUxOThhNDUyNjljNTNjOjc6NTFmNTplOTY5NmFlODA1YWU3NWMwZjk5OGU3MmJkZTRhMWJhZWQ1MjE2MjQ5ODAyNjE3YjRmZDFlMDA4OTkwODljOWNjOnA6VDpG&amp;esheet=54596783&amp;newsitemid=20260831160325&amp;lan=pt-BR&amp;anchor=http%3A%2F%2Fwww.itcinfotech.com.&amp;index=1&amp;md5=5d680108fe69ac670659c9ca3195d0a0\" rel=\"follow\" shape=\"rect\" target=\"_blank\">http:\/\/www.itcinfotech.com.<\/a><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Sobre a Happiest Minds Technologies Limited:<\/b><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA Happiest Minds Technologies Limited \u00e9 uma empresa de engenharia digital centrada no cliente e com foco em IA, comprometida em proporcionar &#8220;Pessoas Mais Felizes. Clientes Mais Felizes&#8221;. Com uma abordagem integrada que abrange desde o chip at\u00e9 a nuvem, a Happiest Minds oferece solu\u00e7\u00f5es seguras e escal\u00e1veis \u200b\u200bem plataformas de engenharia de produtos, ciberseguran\u00e7a, an\u00e1lise de dados e automa\u00e7\u00e3o. A Happiest Minds traz prop\u00f3sito e precis\u00e3o a cada projeto, ajudando empresas a resolver desafios complexos de neg\u00f3cios e acelerar sua evolu\u00e7\u00e3o digital em diversos setores, como Bancos, Servi\u00e7os Financeiros e Seguros (BFSI), EdTech, Sa\u00fade e Ci\u00eancias da Vida, Alta Tecnologia e M\u00eddia e Entretenimento, Ind\u00fastria, Manufatura, Energia e Servi\u00e7os P\u00fablicos, e Varejo, Bens de Consumo e Log\u00edstica.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA Happiest Minds foi homenageada pelo Golden Peacock Awards e pelo Instituto de Secret\u00e1rios de Empresas da \u00cdndia (ICSI) por suas pr\u00e1ticas exemplares de Governan\u00e7a Corporativa. Guiada por sua miss\u00e3o de &#8220;Pessoas Mais Felizes. Clientes Mais Felizes&#8221; e consistentemente reconhecida como um excelente lugar para trabalhar, a Happiest Minds tem sede em Bengaluru, \u00cdndia, com presen\u00e7a global nas Am\u00e9ricas, Reino Unido, Europa, Austr\u00e1lia, Oriente M\u00e9dio, \u00c1frica e \u00c1sia.<\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n<tr>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n____________________<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin\"><sup>[1]<\/sup> Em base pro-forma<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nO texto no idioma original deste an\u00fancio \u00e9 a vers\u00e3o oficial autorizada. As tradu\u00e7\u00f5es s\u00e3o fornecidas apenas como uma facilidade e devem se referir ao texto no idioma original, que \u00e9 a \u00fanica vers\u00e3o do texto que tem efeito legal.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp\"><span class=\"bwct31415\"><\/span><\/p>\n<p id=\"mmgallerylink\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><span id=\"mmgallerylink-phrase\">Ver a vers\u00e3o original em businesswire.com: <\/span><span id=\"mmgallerylink-link\"><a href=\"https:\/\/www.businesswire.com\/news\/home\/20260831160325\/pt\/\" rel=\"follow\" target=\"_blank\">https:\/\/www.businesswire.com\/news\/home\/20260831160325\/pt\/<\/a><\/span><\/p>\n<p><b>Contato:<\/b><\/p>\n<p>\nNazeeb Arif\n<\/p>\n<p><a href=\"mailto:nazeeb.Arif@itc.in\" rel=\"follow\" shape=\"rect\">nazeeb.Arif@itc.in<br \/>\n<\/a><\/p>\n<p>Vice-Presidente Executivo e Chefe de\n<\/p>\n<p>Comunica\u00e7\u00e3o Corporativa,\n<\/p>\n<p>ITC Limited<\/p>\n<p><strong>Fonte: <\/strong><a href='http:\/\/www.businesswire.com\/portal\/site\/home\/' target='_blank'>BUSINESS WIRE<\/a><img src='https:\/\/api.dino.com.br\/v2\/news\/tr\/336573?partnerId=4593' alt=\"\" style=\"border:0px;width:1px;height:1px;\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conselho da ITC Infotech aprova proposta de aquisi\u00e7\u00e3o de 22,1% da participa\u00e7\u00e3o do controlador e um Plano de Fus\u00e3o das duas empresas<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","page_builder":"","footnotes":""},"categories":[315],"tags":[341,331,337,324,323],"class_list":["post-34845","post","type-post","status-publish","format-standard","category-noticias-corporativas-dino","tag-economia","tag-engenharia","tag-entretenimento","tag-negocios","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1] - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angelboss.com.br\/en\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1] - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"og:description\" content=\"Conselho da ITC Infotech aprova proposta de aquisi\u00e7\u00e3o de 22,1% da participa\u00e7\u00e3o do controlador e um Plano de Fus\u00e3o das duas empresas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angelboss.com.br\/en\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp\" \/>\n<meta name=\"author\" content=\"DINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/\"},\"author\":{\"name\":\"DINO\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\"},\"headline\":\"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1]\",\"datePublished\":\"2026-09-01T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/\"},\"wordCount\":1295,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp\",\"keywords\":[\"ECONOMIA\",\"ENGENHARIA\",\"ENTRETENIMENTO\",\"NEG\u00d3CIOS\",\"TECNOLOGIA\"],\"articleSection\":[\"Not\u00edcias Corporativas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/\",\"name\":\"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1] - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp\",\"datePublished\":\"2026-09-01T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp\",\"contentUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/09\\\/01\\\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/angelboss.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss\",\"description\":\"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil\",\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"alternateName\":\"Maior Portal e Blog de Beleza Masculina e Luxo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angelboss.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"width\":1280,\"height\":1280,\"caption\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\",\"name\":\"DINO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"caption\":\"DINO\"},\"url\":\"http:\\\/\\\/angelboss.com.br\\\/en\\\/author\\\/DINO\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1] - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angelboss.com.br\/en\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/","og_locale":"en_US","og_type":"article","og_title":"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1] - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","og_description":"Conselho da ITC Infotech aprova proposta de aquisi\u00e7\u00e3o de 22,1% da participa\u00e7\u00e3o do controlador e um Plano de Fus\u00e3o das duas empresas","og_url":"https:\/\/angelboss.com.br\/en\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/","og_site_name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","article_published_time":"2026-09-01T00:00:00+00:00","og_image":[{"url":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp","type":"","width":"","height":""}],"author":"DINO","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DINO","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/#article","isPartOf":{"@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/"},"author":{"name":"DINO","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5"},"headline":"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1]","datePublished":"2026-09-01T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/"},"wordCount":1295,"commentCount":0,"publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"image":{"@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/#primaryimage"},"thumbnailUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp","keywords":["ECONOMIA","ENGENHARIA","ENTRETENIMENTO","NEG\u00d3CIOS","TECNOLOGIA"],"articleSection":["Not\u00edcias Corporativas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/","url":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/","name":"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1] - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","isPartOf":{"@id":"https:\/\/angelboss.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/#primaryimage"},"image":{"@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/#primaryimage"},"thumbnailUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp","datePublished":"2026-09-01T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/#primaryimage","url":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp","contentUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260831160325r1&amp;sid=brdno&amp;distro=ftp"},{"@type":"BreadcrumbList","@id":"https:\/\/angelboss.com.br\/2026\/09\/01\/336573-combinacao-estrategica-da-itc-infotech-e-da-happiest-minds-technologies-para-criar-uma-empresa-global-de-servicos-de-tecnologia-escalavel-preparada-para-o-futuro-e-com-foco-em-ia-com-receita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/angelboss.com.br\/"},{"@type":"ListItem","position":2,"name":"Combina\u00e7\u00e3o estrat\u00e9gica da ITC Infotech e da Happiest Minds Technologies para criar uma empresa global de servi\u00e7os de tecnologia escal\u00e1vel, preparada para o futuro e com foco em IA, com receita de US$ 1 bilh\u00e3o at\u00e9 o ano fiscal de 2028[1]"}]},{"@type":"WebSite","@id":"https:\/\/angelboss.com.br\/#website","url":"https:\/\/angelboss.com.br\/","name":"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss","description":"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil","publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"alternateName":"Maior Portal e Blog de Beleza Masculina e Luxo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angelboss.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/angelboss.com.br\/#organization","name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","url":"https:\/\/angelboss.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","contentUrl":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","width":1280,"height":1280,"caption":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss"},"image":{"@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5","name":"DINO","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","caption":"DINO"},"url":"http:\/\/angelboss.com.br\/en\/author\/DINO\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/34845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/comments?post=34845"}],"version-history":[{"count":0,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/34845\/revisions"}],"wp:attachment":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/media?parent=34845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/categories?post=34845"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/tags?post=34845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}