{"id":29249,"date":"2026-07-14T00:00:00","date_gmt":"2026-07-14T00:00:00","guid":{"rendered":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/"},"modified":"2026-07-14T00:00:00","modified_gmt":"2026-07-14T00:00:00","slug":"334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis","status":"publish","type":"post","link":"http:\/\/angelboss.com.br\/en\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/","title":{"rendered":"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis"},"content":{"rendered":"<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA Neuraptive Therapeutics, Inc., empresa de biotecnologia em est\u00e1gio cl\u00ednico focada em les\u00f5es dos nervos perif\u00e9ricos, anunciou hoje que assegurou uma licen\u00e7a exclusiva com a Universidade de Washington em St. Louis para um dispositivo sem fio de estimula\u00e7\u00e3o eletr\u00f4nica biorreabsorv\u00edvel.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nDesenvolvida por pesquisadores da Faculdade de Medicina da Universidade de Washington em colabora\u00e7\u00e3o com a Northwestern University, a tecnologia envia pulsos el\u00e9tricos direcionados a nervos danificados para acelerar a regenera\u00e7\u00e3o. O dispositivo \u00e9 totalmente biorreabsorv\u00edvel, o que significa que se desintegra naturalmente no corpo e n\u00e3o requer uma cirurgia posterior para remo\u00e7\u00e3o.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n&#8220;A Universidade de Washington est\u00e1 entusiasmada em fechar a parceria com uma empresa emergente como a Neuraptive para apoiar o desenvolvimento da plataforma biorreabsorv\u00edvel oriunda dos nossos laborat\u00f3rios de pesquisa&#8221;, afirmou Nichole R. Mercier, PhD, vice-reitora assistente e diretora-gerente do Escrit\u00f3rio de Gest\u00e3o de Tecnologia da Universidade de Washington . &#8220;Este acordo permite que a plataforma seja desenvolvida ainda mais para avan\u00e7ar com o reparo de nervos perif\u00e9ricos e gerar impacto nos pacientes&#8221;.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nBob Radie, presidente e CEO da Neuraptive Therapeutics, afirmou: &#8220;Este acordo \u00e9 um passo significativo no fortalecimento do nosso portf\u00f3lio e no fornecimento de mais op\u00e7\u00f5es aos pacientes com les\u00f5es nos nervos. O estimulador biorreabsorv\u00edvel tem um potencial real por si pr\u00f3prio no que diz respeito a reparar nervos danificados ou como um complemento sin\u00e9rgico ao nosso principal produto candidato, o NTX-001. Tamb\u00e9m pretendemos dar continuidade \u00e0s promissoras pesquisas anteriores sobre a capacidade do dispositivo de ajudar a acelerar a recupera\u00e7\u00e3o de nervos danificados. Em geral, essa tecnologia pode dar um conjunto maior de ferramentas aos cirurgi\u00f5es e pacientes, almejando melhor recupera\u00e7\u00e3o funcional, menos problemas a longo prazo e melhor qualidade de vida ap\u00f3s essas les\u00f5es desafiadoras&#8221;.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nO novo dispositivo complementa o pipeline existente da Neuraptive, incluindo o NTX-001, que est\u00e1 atualmente em um ensaio de Fase 3 sobre o reparo cir\u00fargico de nervos perif\u00e9ricos seccionados. Ele se alinha perfeitamente com a estrat\u00e9gia da empresa de combinar terap\u00eautica, entregar sistemas e possibilitar tecnologias para satisfazer necessidades n\u00e3o atendidas nesse espa\u00e7o. Os termos financeiros do acordo de licenciamento n\u00e3o foram divulgados.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Sobre a Neuraptive<br \/>\n<br \/><\/b>A Neuraptive Therapeutics, Inc. \u00e9 uma empresa de biotecnologia dedicada ao desenvolvimento de novas terapias e produtos m\u00e9dicos para satisfazer as necessidades n\u00e3o atendidas de m\u00e9dicos e pacientes afetados por les\u00f5es nos nervos perif\u00e9ricos. O principal programa da empresa, NTX-001, \u00e9 um sistema de fus\u00e3o nervosa concebida para restaurar a continuidade el\u00e9trica em nervos danificados. Para mais informa\u00e7\u00f5es, acesse <a href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fnam10.safelinks.protection.outlook.com%2F%3Furl%3Dhttp%253A%252F%252Fwww.neuraptive.com%252F%26data%3D05%257C02%257Cleslie.roettger%2540wustl.edu%257C52d0059c237a47c3abc508ded7b0b846%257C4ccca3b571cd4e6d974b4d9beb96c6d6%257C0%257C0%257C639185351202437711%257CUnknown%257CTWFpbGZsb3d8eyJFbXB0eU1hcGkiOnRydWUsIlYiOiIwLjAuMDAwMCIsIlAiOiJXaW4zMiIsIkFOIjoiTWFpbCIsIldUIjoyfQ%253D%253D%257C0%257C%257C%257C%26sdata%3D%252F%252BrbBxC53EagxNWWFqaQB2K6tmTHxWVFo%252Bln8mIWglg%253D%26reserved%3D0&amp;esheet=54569155&amp;newsitemid=20260714158724&amp;lan=pt-BR&amp;anchor=www.neuraptive.com&amp;index=1&amp;md5=09153270415ec616619b99a327af5e7e\" rel=\"follow\" shape=\"rect\" target=\"_blank\">www.neuraptive.com<\/a>.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nO texto no idioma original deste an\u00fancio \u00e9 a vers\u00e3o oficial autorizada. As tradu\u00e7\u00f5es s\u00e3o fornecidas apenas como uma facilidade e devem se referir ao texto no idioma original, que \u00e9 a \u00fanica vers\u00e3o do texto que tem efeito legal.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp\"><span class=\"bwct31415\"><\/span><\/p>\n<p id=\"mmgallerylink\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><span id=\"mmgallerylink-phrase\">Ver a vers\u00e3o original em businesswire.com: <\/span><span id=\"mmgallerylink-link\"><a href=\"https:\/\/www.businesswire.com\/news\/home\/20260714158724\/pt\/\" rel=\"follow\" target=\"_blank\">https:\/\/www.businesswire.com\/news\/home\/20260714158724\/pt\/<\/a><\/span><\/p>\n<p><b>Contato:<\/b><\/p>\n<p><a href=\"mailto:IR@neuraptive.com\" rel=\"follow\" shape=\"rect\">IR@neuraptive.com<br \/>\n<\/a><\/p>\n<p>ou\n<\/p>\n<p>+1-484-787-3203<\/p>\n<p><strong>Fonte: <\/strong><a href='http:\/\/www.businesswire.com\/portal\/site\/home\/' target='_blank'>BUSINESS WIRE<\/a><img src='https:\/\/api.dino.com.br\/v2\/news\/tr\/334073?partnerId=4593' alt=\"\" style=\"border:0px;width:1px;height:1px;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>A Neuraptive Therapeutics, Inc., empresa de biotecnologia em est\u00e1gio cl\u00ednico focada em les\u00f5es dos nervos perif\u00e9ricos, anunciou hoje que assegurou uma licen\u00e7a exclusiva com a Universidade de Washington em St. Louis para um dispositivo sem fio de estimula\u00e7\u00e3o eletr\u00f4nica biorreabsorv\u00edvel. Desenvolvida por pesquisadores da Faculdade de Medicina da Universidade de Washington em colabora\u00e7\u00e3o com a<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[315],"tags":[324,352],"class_list":["post-29249","post","type-post","status-publish","format-standard","category-noticias-corporativas-dino","tag-negocios","tag-saude-e-bem-estar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"og:description\" content=\"A Neuraptive Therapeutics, Inc., empresa de biotecnologia em est\u00e1gio cl\u00ednico focada em les\u00f5es dos nervos perif\u00e9ricos, anunciou hoje que assegurou uma licen\u00e7a exclusiva com a Universidade de Washington em St. Louis para um dispositivo sem fio de estimula\u00e7\u00e3o eletr\u00f4nica biorreabsorv\u00edvel. Desenvolvida por pesquisadores da Faculdade de Medicina da Universidade de Washington em colabora\u00e7\u00e3o com a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp\" \/>\n<meta name=\"author\" content=\"DINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/\"},\"author\":{\"name\":\"DINO\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\"},\"headline\":\"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis\",\"datePublished\":\"2026-07-14T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/\"},\"wordCount\":539,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp\",\"keywords\":[\"NEG\u00d3CIOS\",\"SA\u00daDE E BEM-ESTAR\"],\"articleSection\":[\"Not\u00edcias Corporativas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/\",\"name\":\"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp\",\"datePublished\":\"2026-07-14T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp\",\"contentUrl\":\"https:\\\/\\\/cts.businesswire.com\\\/ct\\\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/07\\\/14\\\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/angelboss.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss\",\"description\":\"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil\",\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"alternateName\":\"Maior Portal e Blog de Beleza Masculina e Luxo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angelboss.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"width\":1280,\"height\":1280,\"caption\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\",\"name\":\"DINO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"caption\":\"DINO\"},\"url\":\"http:\\\/\\\/angelboss.com.br\\\/en\\\/author\\\/DINO\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/","og_locale":"en_US","og_type":"article","og_title":"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","og_description":"A Neuraptive Therapeutics, Inc., empresa de biotecnologia em est\u00e1gio cl\u00ednico focada em les\u00f5es dos nervos perif\u00e9ricos, anunciou hoje que assegurou uma licen\u00e7a exclusiva com a Universidade de Washington em St. Louis para um dispositivo sem fio de estimula\u00e7\u00e3o eletr\u00f4nica biorreabsorv\u00edvel. Desenvolvida por pesquisadores da Faculdade de Medicina da Universidade de Washington em colabora\u00e7\u00e3o com a","og_url":"https:\/\/angelboss.com.br\/en\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/","og_site_name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","article_published_time":"2026-07-14T00:00:00+00:00","og_image":[{"url":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp","type":"","width":"","height":""}],"author":"DINO","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DINO","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/#article","isPartOf":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/"},"author":{"name":"DINO","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5"},"headline":"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis","datePublished":"2026-07-14T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/"},"wordCount":539,"commentCount":0,"publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"image":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/#primaryimage"},"thumbnailUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp","keywords":["NEG\u00d3CIOS","SA\u00daDE E BEM-ESTAR"],"articleSection":["Not\u00edcias Corporativas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/","url":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/","name":"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","isPartOf":{"@id":"https:\/\/angelboss.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/#primaryimage"},"image":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/#primaryimage"},"thumbnailUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp","datePublished":"2026-07-14T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/#primaryimage","url":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp","contentUrl":"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260714158724r1&amp;sid=brdno&amp;distro=ftp"},{"@type":"BreadcrumbList","@id":"https:\/\/angelboss.com.br\/2026\/07\/14\/334073-neuraptive-therapeutics-licencia-inovadora-tecnologia-de-estimulacao-nervosa-biorreabsorvivel-com-a-universidade-de-washington-em-st-louis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/angelboss.com.br\/"},{"@type":"ListItem","position":2,"name":"Neuraptive Therapeutics licencia inovadora tecnologia de estimula\u00e7\u00e3o nervosa biorreabsorv\u00edvel com a Universidade de Washington em St. Louis"}]},{"@type":"WebSite","@id":"https:\/\/angelboss.com.br\/#website","url":"https:\/\/angelboss.com.br\/","name":"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss","description":"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil","publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"alternateName":"Maior Portal e Blog de Beleza Masculina e Luxo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angelboss.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/angelboss.com.br\/#organization","name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","url":"https:\/\/angelboss.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","contentUrl":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","width":1280,"height":1280,"caption":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss"},"image":{"@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5","name":"DINO","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","caption":"DINO"},"url":"http:\/\/angelboss.com.br\/en\/author\/DINO\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/29249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/comments?post=29249"}],"version-history":[{"count":0,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/29249\/revisions"}],"wp:attachment":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/media?parent=29249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/categories?post=29249"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/tags?post=29249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}