{"id":23232,"date":"2026-05-19T00:00:00","date_gmt":"2026-05-19T00:00:00","guid":{"rendered":"https:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/"},"modified":"2026-05-19T00:00:00","modified_gmt":"2026-05-19T00:00:00","slug":"331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes","status":"publish","type":"post","link":"http:\/\/angelboss.com.br\/en\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/","title":{"rendered":"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes"},"content":{"rendered":"<ul>\n<li>Planta modular a diesel de 20 MW fornecer\u00e1 energia principal para a constru\u00e7\u00e3o de dois shafts da mina e, posteriormente, atuar\u00e1 como sistema de backup emergencial durante os primeiros 23 anos de opera\u00e7\u00e3o do projeto;<\/li>\n<li>Gera Center foi selecionada por meio de processo competitivo com participa\u00e7\u00e3o de 12 empresas com experi\u00eancia na Amaz\u00f4nia; contrato prev\u00ea mobiliza\u00e7\u00e3o em at\u00e9 120 dias para in\u00edcio do fornecimento de energia e disponibilidade operacional contratual de 98% na fase de backup;<\/li>\n<li>Estrutura BOOT transfere aproximadamente US$ 33 milh\u00f5es em investimentos de gera\u00e7\u00e3o de energia do or\u00e7amento inicial de constru\u00e7\u00e3o da Brazil Potash para custos operacionais distribu\u00eddos ao longo de 28 anos, al\u00e9m de gerar economia estimada em cerca de US$ 10 milh\u00f5es em rela\u00e7\u00e3o ao Estudo de Pr\u00e9-Viabilidade do projeto.<\/li>\n<\/ul>\n<p>MANAUS, Brazil, May 19, 2026 (GLOBE NEWSWIRE) &#8212; A Brazil Potash (NYSE-American: GRO), companhia de explora\u00e7\u00e3o e desenvolvimento mineral respons\u00e1vel pelo Projeto Pot\u00e1ssio Autazes, anunciou hoje a assinatura de um Memorando de Entendimentos (MOU, na sigla em ingl\u00eas) n\u00e3o vinculante com a Gera Center para a implanta\u00e7\u00e3o de um contrato no modelo Build, Own, Operate and Transfer (BOOT), com dura\u00e7\u00e3o de 28 anos, destinado ao fornecimento de energia para o projeto no Amazonas.<\/p>\n<p>O acordo prev\u00ea a instala\u00e7\u00e3o de uma planta modular de gera\u00e7\u00e3o de energia a diesel que atuar\u00e1 como fonte principal de energia durante a fase de constru\u00e7\u00e3o do empreendimento e, posteriormente, como sistema emergencial de backup ao longo dos primeiros 23 anos de opera\u00e7\u00e3o da mina.<\/p>\n<p>A Gera Center foi selecionada ap\u00f3s processo competitivo formal conduzido pela Brazil Potash, envolvendo empresas com experi\u00eancia comprovada na regi\u00e3o amaz\u00f4nica. Segundo a companhia, a estrutura BOOT permitir\u00e1 transferir aproximadamente US$ 33 milh\u00f5es em investimentos iniciais de gera\u00e7\u00e3o de energia do or\u00e7amento de constru\u00e7\u00e3o do projeto para custos operacionais dilu\u00eddos ao longo de 28 anos. O modelo tamb\u00e9m dever\u00e1 gerar economia l\u00edquida estimada em cerca de US$ 10 milh\u00f5es ao longo da vida do contrato, em compara\u00e7\u00e3o aos valores previstos no Estudo de Pr\u00e9-Viabilidade (PFS) do projeto.<\/p>\n<p>&quot;Este acordo BOOT com a Gera Center fornece energia confi\u00e1vel para a constru\u00e7\u00e3o em uma localidade onde a rede el\u00e9trica ainda n\u00e3o est\u00e1 dispon\u00edvel, ao mesmo tempo em que reduz os custos iniciais de implanta\u00e7\u00e3o do projeto,&quot; afirma Matt Simpson. &quot;A Gera Center foi selecionada por meio de um processo competitivo rigoroso, e sua proposta ficou cerca de US$ 10 milh\u00f5es abaixo das estimativas do nosso PFS ao longo da vida do projeto. A mesma planta que fornecer\u00e1 energia para a constru\u00e7\u00e3o passar\u00e1 a atuar como sistema de backup emergencial durante toda a vida \u00fatil da mina, sendo um dos at\u00e9 cinco contratos BOOT que a companhia est\u00e1 estruturando como parte da estrat\u00e9gia de financiamento da constru\u00e7\u00e3o do projeto.&quot;<\/p>\n<p><strong>Detalhes do acordo<\/strong><\/p>\n<p>Pelos termos do MOU, a Gera Center ser\u00e1 respons\u00e1vel pelo fornecimento, instala\u00e7\u00e3o, opera\u00e7\u00e3o e manuten\u00e7\u00e3o de 63 grupos geradores modulares containerizados movidos a diesel, com capacidade m\u00e1xima de 20 megawatts (MW).<\/p>\n<p>O sistema ser\u00e1 implantado de forma escalonada, acompanhando o crescimento da demanda energ\u00e9tica da constru\u00e7\u00e3o, iniciando com 10 MW e alcan\u00e7ando 20 MW ao longo do primeiro ano. O primeiro fornecimento de energia poder\u00e1 ocorrer em at\u00e9 120 dias ap\u00f3s a assinatura do contrato definitivo.<\/p>\n<p>Como n\u00e3o h\u00e1 disponibilidade de energia da rede convencional no local durante a fase de implanta\u00e7\u00e3o, a planta atender\u00e1 integralmente as atividades de obras civis e escava\u00e7\u00e3o dos shafts da mina.<\/p>\n<p>Ap\u00f3s o in\u00edcio das opera\u00e7\u00f5es, o sistema passar\u00e1 a atuar como solu\u00e7\u00e3o emergencial de backup por 23 anos, garantindo continuidade operacional em caso de interrup\u00e7\u00e3o da linha principal de transmiss\u00e3o de 500 kV que conectar\u00e1 o projeto ao Sistema Interligado Nacional (SIN).<\/p>\n<p>O contrato prev\u00ea disponibilidade operacional m\u00ednima de 98% durante essa fase, al\u00e9m de tempo m\u00e1ximo de resposta de duas horas para incidentes cr\u00edticos. Ao final do contrato de 28 anos, toda a infraestrutura de gera\u00e7\u00e3o ser\u00e1 transferida para a Brazil Potash.<\/p>\n<p><strong>Processo competitivo<\/strong><\/p>\n<p>A sele\u00e7\u00e3o da Gera Center foi conduzida pelo diretor de projetos da Brazil Potash, Raphael Bloise, por meio de processo competitivo formal com participa\u00e7\u00e3o de 12 empresas com experi\u00eancia comprovada na regi\u00e3o amaz\u00f4nica.<\/p>\n<p>Ao todo:<\/p>\n<ul>\n<li>12 empresas foram convidadas;<\/li>\n<li>8 apresentaram propostas formais;<\/li>\n<li>4 foram selecionadas para a fase final de avalia\u00e7\u00e3o.<\/li>\n<\/ul>\n<p>As propostas passaram por refinamentos t\u00e9cnicos e comerciais em reuni\u00f5es presenciais e virtuais com as equipes t\u00e9cnicas envolvidas.<\/p>\n<p>Segundo a Brazil Potash, a Gera Center obteve a melhor avalia\u00e7\u00e3o t\u00e9cnica e comercial considerando todo o horizonte contratual de 28 anos, gerando aproximadamente US$ 10 milh\u00f5es em economia em rela\u00e7\u00e3o ao or\u00e7amento previsto no PFS e refor\u00e7ando a estrat\u00e9gia da companhia de estruturar no modelo BOOT grande parte das infraestruturas n\u00e3o essenciais do projeto.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><\/p>\n<p>As partes trabalhar\u00e3o nos pr\u00f3ximos meses para a formaliza\u00e7\u00e3o dos contratos definitivos.<\/p>\n<p>A companhia ressalta que o MOU possui car\u00e1ter n\u00e3o vinculante e, portanto, n\u00e3o h\u00e1 garantia de que os contratos definitivos ser\u00e3o assinados, nem de que a transa\u00e7\u00e3o ser\u00e1 conclu\u00edda nos termos atualmente previstos.<\/p>\n<p>A expectativa \u00e9 que o sistema esteja totalmente instalado e fornecendo energia principal para a constru\u00e7\u00e3o dentro da janela de mobiliza\u00e7\u00e3o de 120 dias ap\u00f3s a assinatura dos contratos definitivos, em alinhamento com o cronograma de escava\u00e7\u00e3o dos shafts do Projeto Pot\u00e1ssio Autazes.<\/p>\n<p><strong>Sobre a Gera Center<\/strong><\/p>\n<p>Fundada em 1991, a Gera Center \u00e9 uma empresa brasileira especializada em solu\u00e7\u00f5es cr\u00edticas de gera\u00e7\u00e3o de energia para os setores industrial, minera\u00e7\u00e3o, agroneg\u00f3cio, infraestrutura e constru\u00e7\u00e3o.<\/p>\n<p>Com sede em Manaus, atua na engenharia, instala\u00e7\u00e3o, opera\u00e7\u00e3o e manuten\u00e7\u00e3o de sistemas turnkey de gera\u00e7\u00e3o modular a diesel, incluindo opera\u00e7\u00f5es remotas e de alta complexidade log\u00edstica na regi\u00e3o amaz\u00f4nica.<\/p>\n<p>No Projeto Pot\u00e1ssio Autazes, a empresa prev\u00ea a implanta\u00e7\u00e3o de uma planta modular de 20 MW com tecnologia de alta densidade energ\u00e9tica, projetada para otimizar efici\u00eancia operacional e minimizar impactos ambientais.<\/p>\n<p>O projeto dever\u00e1 gerar aproximadamente 200 empregos diretos e indiretos durante as fases de implanta\u00e7\u00e3o e opera\u00e7\u00e3o.<\/p>\n<p><strong>Sobre a Brazil Potash<\/strong><\/p>\n<p>A Brazil Potash, por meio de sua subsidi\u00e1ria integral Pot\u00e1ssio do Brasil, est\u00e1 desenvolvendo o Projeto Pot\u00e1ssio Autazes com o objetivo de ampliar o fornecimento nacional de fertilizantes para o agroneg\u00f3cio brasileiro.<\/p>\n<p>O Brasil importou mais de 95% do pot\u00e1ssio utilizado no pa\u00eds em 2021, apesar de possuir uma das maiores bacias de pot\u00e1ssio ainda n\u00e3o desenvolvidas do mundo.<\/p>\n<p>A produ\u00e7\u00e3o do projeto dever\u00e1 ser transportada prioritariamente por meio de barca\u00e7as fluviais em parceria com a Amaggi, uma das maiores empresas brasileiras do setor agroindustrial e log\u00edstico.<\/p>\n<p>Com capacidade inicial planejada de at\u00e9 2,4 milh\u00f5es de toneladas anuais de pot\u00e1ssio, a companhia estima potencial para atender aproximadamente 20% da demanda atual do Brasil pelo insumo.<\/p>\n<p>A expectativa da empresa \u00e9 destinar 100% da produ\u00e7\u00e3o ao mercado brasileiro, contribuindo para reduzir a depend\u00eancia de importa\u00e7\u00f5es e mitigar aproximadamente 1,4 milh\u00e3o de toneladas anuais de emiss\u00f5es de gases de efeito estufa.<\/p>\n<p><strong>Contato para imprensa e investidores<\/strong><\/p>\n<p><a href=\"https:\/\/www.globenewswire.com\/Tracker?data=Y7Ww8cdg9PQ7ZkBLzRrpN-_UirHft5CDVoLAYNYypCvVhEQ2-dIGXSRVSaW05FzWrrY44EWk8iCI4PWMTrzcXtxfN_ur2dEP4Tb2FXng9aauN2u6hnbROsL3w5saWzSNLeTgb6YmzqfB1_dhqYouag==\" rel=\"follow\" target=\"_blank\">imprensa@potassiodobrasil.com.br<\/a><\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/ml.globenewswire.com\/media\/NDkzZTE1ZTAtMTcwYy00YmZkLTkyNTAtYzFlNTFiNmI1OWVlLTEyNDQyMzQtMjAyNi0wNS0xOS1wdA==\/tiny\/BRAZIL-POTASH-CORP.png\"><\/p>\n<p><a href=\"https:\/\/www.globenewswire.com\/NewsRoom\/AttachmentNg\/2db3213b-1d91-4431-a3b7-9d85c76f9226\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/ml.globenewswire.com\/media\/2db3213b-1d91-4431-a3b7-9d85c76f9226\/small\/brazil-potash-logo-jpg.jpg\" alt=\"Primary Logo\"><\/a><\/p>\n<p> GLOBENEWSWIRE (Distribution ID 9723013)<img src='https:\/\/api.dino.com.br\/v2\/news\/tr\/331360?partnerId=4593' alt=\"\" style=\"border:0px;width:1px;height:1px;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Estrutura elimina aproximadamente US$ 33 milh\u00f5es em CAPEX inicial de constru\u00e7\u00e3o e projeta economia l\u00edquida de cerca de US$ 10 milh\u00f5es ao longo do contrato<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[315],"tags":[337,357,323],"class_list":["post-23232","post","type-post","status-publish","format-standard","category-noticias-corporativas-dino","tag-entretenimento","tag-estilo-de-vida","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/angelboss.com.br\/en\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"og:description\" content=\"Estrutura elimina aproximadamente US$ 33 milh\u00f5es em CAPEX inicial de constru\u00e7\u00e3o e projeta economia l\u00edquida de cerca de US$ 10 milh\u00f5es ao longo do contrato\" \/>\n<meta property=\"og:url\" content=\"http:\/\/angelboss.com.br\/en\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-19T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=\" \/>\n<meta name=\"author\" content=\"DINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/\"},\"author\":{\"name\":\"DINO\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\"},\"headline\":\"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes\",\"datePublished\":\"2026-05-19T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/\"},\"wordCount\":1260,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.globenewswire.com\\\/newsroom\\\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=\",\"keywords\":[\"ENTRETENIMENTO\",\"ESTILO DE VIDA\",\"TECNOLOGIA\"],\"articleSection\":[\"Not\u00edcias Corporativas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/\",\"url\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/\",\"name\":\"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.globenewswire.com\\\/newsroom\\\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=\",\"datePublished\":\"2026-05-19T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.globenewswire.com\\\/newsroom\\\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=\",\"contentUrl\":\"https:\\\/\\\/www.globenewswire.com\\\/newsroom\\\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/19\\\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/angelboss.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss\",\"description\":\"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil\",\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"alternateName\":\"Maior Portal e Blog de Beleza Masculina e Luxo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angelboss.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"width\":1280,\"height\":1280,\"caption\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\",\"name\":\"DINO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"caption\":\"DINO\"},\"url\":\"http:\\\/\\\/angelboss.com.br\\\/en\\\/author\\\/DINO\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/angelboss.com.br\/en\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/","og_locale":"en_US","og_type":"article","og_title":"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","og_description":"Estrutura elimina aproximadamente US$ 33 milh\u00f5es em CAPEX inicial de constru\u00e7\u00e3o e projeta economia l\u00edquida de cerca de US$ 10 milh\u00f5es ao longo do contrato","og_url":"http:\/\/angelboss.com.br\/en\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/","og_site_name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","article_published_time":"2026-05-19T00:00:00+00:00","og_image":[{"url":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=","type":"","width":"","height":""}],"author":"DINO","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DINO","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/#article","isPartOf":{"@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/"},"author":{"name":"DINO","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5"},"headline":"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes","datePublished":"2026-05-19T00:00:00+00:00","mainEntityOfPage":{"@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/"},"wordCount":1260,"commentCount":0,"publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"image":{"@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=","keywords":["ENTRETENIMENTO","ESTILO DE VIDA","TECNOLOGIA"],"articleSection":["Not\u00edcias Corporativas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/","url":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/","name":"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","isPartOf":{"@id":"https:\/\/angelboss.com.br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/#primaryimage"},"image":{"@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=","datePublished":"2026-05-19T00:00:00+00:00","breadcrumb":{"@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/#primaryimage","url":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE=","contentUrl":"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=OTcyMzAxMyM3NjEwOTk2IzIyMzI2ODE="},{"@type":"BreadcrumbList","@id":"http:\/\/angelboss.com.br\/2026\/05\/19\/331360-brazil-potash-assina-memorando-de-entendimento-com-a-gera-center-para-contrato-boot-de-energia-por-28-anos-no-projeto-potassio-autazes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/angelboss.com.br\/"},{"@type":"ListItem","position":2,"name":"Brazil Potash assina memorando de entendimento com a Gera Center para contrato BOOT de energia por 28 anos no Projeto Pot\u00e1ssio Autazes"}]},{"@type":"WebSite","@id":"https:\/\/angelboss.com.br\/#website","url":"https:\/\/angelboss.com.br\/","name":"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss","description":"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil","publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"alternateName":"Maior Portal e Blog de Beleza Masculina e Luxo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angelboss.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/angelboss.com.br\/#organization","name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","url":"https:\/\/angelboss.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","contentUrl":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","width":1280,"height":1280,"caption":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss"},"image":{"@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5","name":"DINO","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","caption":"DINO"},"url":"http:\/\/angelboss.com.br\/en\/author\/DINO\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/23232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/comments?post=23232"}],"version-history":[{"count":0,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/23232\/revisions"}],"wp:attachment":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/media?parent=23232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/categories?post=23232"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/tags?post=23232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}