{"id":21330,"date":"2026-05-04T00:00:00","date_gmt":"2026-05-04T00:00:00","guid":{"rendered":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/"},"modified":"2026-05-04T00:00:00","modified_gmt":"2026-05-04T00:00:00","slug":"330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica","status":"publish","type":"post","link":"http:\/\/angelboss.com.br\/en\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/","title":{"rendered":"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica"},"content":{"rendered":"<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA OPAQUE, empresa de intelig\u00eancia artificial (IA) confidencial sediada em S\u00e3o Francisco, na Calif\u00f3rnia, anunciou hoje a aquisi\u00e7\u00e3o de tecnologias avan\u00e7adas de IA criptogr\u00e1fica do Technology Innovation Institute (TII), o pilar de pesquisa aplicada do Conselho de Pesquisa em Tecnologia Avan\u00e7ada (ATRC) de Abu Dhabi. A tecnologia adquirida, j\u00e1 comprovada em casos de uso reais, adiciona dois recursos essenciais &agrave; plataforma da OPAQUE: treinamento de modelos de IA confidencial, impulsionado por t\u00e9cnicas criptogr\u00e1ficas avan\u00e7adas, como computa\u00e7\u00e3o multipartid\u00e1ria e criptografia totalmente homom\u00f3rfica, e prote\u00e7\u00f5es criptogr\u00e1ficas p\u00f3s-qu\u00e2nticas.<\/p>\n<p id=\"news-body-cta\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">Este comunicado de imprensa inclui multim\u00e9dia. Veja o comunicado completo aqui: <a href=\"https:\/\/www.businesswire.com\/news\/home\/20260504281129\/pt\/\" rel=\"follow\" target=\"_blank\">https:\/\/www.businesswire.com\/news\/home\/20260504281129\/pt\/<\/a><\/p>\n<div id=\"bwbodyimg\" style=\"width: 480px; float:left; padding-left:0px; padding-right:20px; padding-top:0px; padding-bottom:0px;\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><img decoding=\"async\" src=\"https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2791846\/4\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg\" alt=\"OPAQUE Acquires Abu Dhabi-Developed Cryptographic AI Technology from TII, Extending Confidential AI Across the Full Lifecycle with Post-Quantum Protection (Photo: AETOSWire)\"><\/p>\n<p style=\"font-size:85%;\">OPAQUE Acquires Abu Dhabi-Developed Cryptographic AI Technology from TII, Extending Confidential AI Across the Full Lifecycle with Post-Quantum Protection (Photo: AETOSWire)<\/p>\n<\/div>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nFundada por pesquisadores do RISELab da Universidade da Calif\u00f3rnia em Berkeley, a OPAQUE agora oferece suporte a fluxos de trabalho de IA confidencial em treinamento e infer\u00eancia, levando as empresas de experimentos isolados de IA para a implanta\u00e7\u00e3o em produ\u00e7\u00e3o quatro a cinco vezes mais r\u00e1pido.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA aquisi\u00e7\u00e3o foi supervisionada por Faisal Al Bannai, assessor do presidente dos Emirados \u00c1rabes Unidos, xeque Mohamed bin Zayed Al Nahyan, e secret\u00e1rio-geral do ATRC; e por Ion Stoica, cofundador e membro do conselho da OPAQUE, cofundador da Databricks e professor de ci\u00eancia da computa\u00e7\u00e3o da Universidade da Calif\u00f3rnia em Berkeley. Essa \u00e9 a primeira vez que tecnologias de IA criptogr\u00e1fica desenvolvidas nos Emirados \u00c1rabes Unidos s\u00e3o adquiridas e implementadas em larga escala por uma empresa de tecnologia sediada nos Estados Unidos.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n\u201cEsta aquisi\u00e7\u00e3o reflete o que os Emirados \u00c1rabes Unidos se propuseram a fazer \u2014 produzir tecnologia fundamental que o mundo adota\u201d, afirmou Sua Excel\u00eancia Faisal Al Banna, conselheiro do presidente dos EAU e secret\u00e1rio-geral da ATRC. \u201cAs capacidades de IA criptogr\u00e1fica desenvolvidas em Abu Dhabi est\u00e3o agora sendo implementadas em escala global por uma empresa l\u00edder de tecnologia dos EUA. Os EAU n\u00e3o est\u00e3o apenas adotando a economia de IA \u2014 estamos liderando. A ATRC continuar\u00e1 investindo em pesquisas que definem a pr\u00f3xima gera\u00e7\u00e3o de IA confi\u00e1vel.\u201d<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n\u201cO futuro da IA depende de desbloquear os dados que as organiza\u00e7\u00f5es nunca conseguiram acessar\u201d, afirmou Ion Stoica, cofundador da OPAQUE. \u201cA maioria das empresas possui um conjunto de dados sens\u00edveis demais para serem utilizados e valiosos demais para serem ignorados. Com esta aquisi\u00e7\u00e3o, a OPAQUE \u00e9 a \u00fanica plataforma que fornece evid\u00eancias criptogr\u00e1ficas atestadas por hardware ao longo de todo o ciclo de vida da IA \u2014 treinamento, ajuste fino, infer\u00eancia e agentes \u2014 com prote\u00e7\u00f5es projetadas para resistir a amea\u00e7as da era qu\u00e2ntica. Essa combina\u00e7\u00e3o n\u00e3o existe em nenhum outro lugar no mercado atualmente.\u201d<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n\u201cAgentes de IA s\u00e3o extraordinariamente poderosos: operam em velocidade de m\u00e1quina com capacidades semelhantes \u00e0s humanas, entregando em dias o que equipes inteiras teriam dificuldade para concluir em um ano\u201d, disse Aaron Fulkerson, diretor-executivo da OPAQUE. \u201cEsse mesmo poder \u00e9 exatamente o motivo pelo qual eles s\u00e3o t\u00e3o dif\u00edceis de colocar em produ\u00e7\u00e3o. Um agente conectado a sistemas sens\u00edveis ou dados regulados \u2014 prontu\u00e1rios de pacientes, pesquisas cl\u00ednicas, reivindica\u00e7\u00f5es financeiras \u2014 pode causar danos em dias que uma equipe de agentes mal-intencionados n\u00e3o conseguiria igualar em um ano. A \u00fanica maneira de implant\u00e1-los com seguran\u00e7a \u00e9 com regras verific\u00e1veis e aplicadas por hardware: evid\u00eancias comprov\u00e1veis do que foi executado, onde foi executado e quais regras foram aplicadas. Com base em primitivas de todos os principais provedores de nuvem, a OPAQUE torna poss\u00edvel levar agentes para produ\u00e7\u00e3o \u2014 mesmo nos sistemas e dados mais sens\u00edveis e mais regulados.\u201d<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nAs empresas acumulam enormes quantidades de dados sens\u00edveis, como prontu\u00e1rios de pacientes, transa\u00e7\u00f5es financeiras, intelig\u00eancia confidencial e pesquisas propriet\u00e1rias, que poderiam transformar suas capacidades de IA. No entanto, utilizar esses dados ao longo de todo o ciclo de vida da IA exigia a integra\u00e7\u00e3o de solu\u00e7\u00f5es pontuais de v\u00e1rios fornecedores, cada uma cobrindo uma fase diferente: uma para treinamento, outra para infer\u00eancia e outra para fluxos de trabalho de agentes. O resultado s\u00e3o lacunas, complexidade e riscos que as equipes de conformidade n\u00e3o aprovam.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA OPAQUE elimina essas lacunas. A tecnologia adquirida amplia a plataforma de IA confidencial da empresa para abranger treinamento, ajuste fino, infer\u00eancia e execu\u00e7\u00e3o de agentes de IA. Ela oferece garantias verific\u00e1veis em cada etapa, apoiadas por criptografia p\u00f3s-qu\u00e2ntica, que protege cargas de trabalho contra amea\u00e7as atuais e futuras. Por exemplo, a ServiceNow utiliza a OPAQUE em produ\u00e7\u00e3o para ampliar as capacidades de IA para seus clientes corporativos, sem expor seus dados. Um sistema nacional de sa\u00fade pode treinar modelos diagn\u00f3sticos com dados de pacientes em diferentes jurisdi\u00e7\u00f5es, executar infer\u00eancia em diversas unidades e implantar agentes de IA em dados cl\u00ednicos em tempo real \u2014 tudo em uma \u00fanica plataforma. A plataforma gera evid\u00eancias atestadas por hardware, alinhadas com SOC 2, ISO 27001, ISO 42001, o Artigo 32 do GDPR e as obriga\u00e7\u00f5es de alto risco da AI Act (Lei de Intelig\u00eancia Artificial) da UE, comprovando que os dados permaneceram privados, que as pol\u00edticas foram aplicadas e que os requisitos regulat\u00f3rios foram atendidos.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nFundamentalmente, a arquitetura da OPAQUE significa que a aplica\u00e7\u00e3o criptogr\u00e1fica est\u00e1 enraizada no hardware, e n\u00e3o na confian\u00e7a no fornecedor. Os dados dos clientes \u2014 inclusive os processados por programas de IA soberanos e por empresas regulamentadas \u2014 permanecem protegidos por Ambientes de Execu\u00e7\u00e3o Confi\u00e1veis e por atestados verific\u00e1veis, aos quais nem mesmo a pr\u00f3pria OPAQUE tem acesso. Isso permite que a plataforma seja implantada em infraestruturas de nuvem soberanas em todo o mundo, com prova criptogr\u00e1fica da localiza\u00e7\u00e3o dos dados. Dessa forma, programas nacionais de IA podem adotar a IA confidencial sem abrir m\u00e3o do controle dos dados no territ\u00f3rio nacional ou da soberania jurisdicional.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nEm setores de alto risco, esses desafios surgem sempre que os sistemas de IA dependem de dados confidenciais, como no caso de bancos que treinam modelos de detec\u00e7\u00e3o de fraudes em diferentes jurisdi\u00e7\u00f5es regulat\u00f3rias, empresas do setor de defesa que ajustam modelos com base em informa\u00e7\u00f5es sigilosas e fornecedores de software que incorporam IA em produtos que lidam com dados de clientes.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nA aquisi\u00e7\u00e3o ocorre ap\u00f3s a rodada de financiamento S\u00e9rie B da OPAQUE no valor de US$ 24 milh\u00f5es, com avalia\u00e7\u00e3o de US$ 300 milh\u00f5es, e se baseia em uma carteira de clientes que inclui ServiceNow, Anthropic, Accenture e Encore Capital. Com a tecnologia adquirida, a OPAQUE oferece suporte a fluxos de trabalho de IA confidencial em treinamento, ajuste fino, infer\u00eancia e agentes, levando empresas e programas de IA soberanos de experimentos isolados para a implanta\u00e7\u00e3o em produ\u00e7\u00e3o de quatro a cinco vezes mais r\u00e1pido, com seguran\u00e7a verific\u00e1vel e prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nPara a TII e a ATRC, a transa\u00e7\u00e3o valida uma estrat\u00e9gia deliberada: investir em pesquisa fundamental em criptografia, comprov\u00e1-la em modelos de linguagem de classe mundial e, posteriormente, distribu\u00ed-la globalmente por meio de parceiros que tenham a plataforma e a base de clientes necess\u00e1rias para escal\u00e1-la. A tecnologia fundamental de IA desenvolvida em Abu Dhabi ser\u00e1 implantada em servi\u00e7os financeiros, sa\u00fade, governo e SaaS corporativo em todos os continentes, estabelecendo os Emirados \u00c1rabes Unidos como um produtor da infraestrutura criptogr\u00e1fica que alimenta a pr\u00f3xima gera\u00e7\u00e3o de IA confi\u00e1vel.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\n\u201cDesenvolvemos essas tecnologias criptogr\u00e1ficas para enfrentar um desafio fundamental da IA: como permitir que modelos poderosos trabalhem com dados altamente sens\u00edveis sem comprometer a confidencialidade ou a confian\u00e7a\u201d, afirmou a Dra. Najwa Aaraj, diretora-executiva da TII. \u201cA OPAQUE foi a parceira certa para levar isso ao mercado, pois j\u00e1 construiu a plataforma empresarial e a base de clientes necess\u00e1rias para implant\u00e1-lo em escala. \u00c9 para isso que serve a pesquisa aplicada \u2014 tecnologia fundamental desenvolvida em Abu Dhabi, agora saindo do laborat\u00f3rio para uma implementa\u00e7\u00e3o global no mundo real.\u201d<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nO an\u00fancio foi divulgado no evento \u201cMake it in the Emirates\u201d (Produza nos Emirados, em tradu\u00e7\u00e3o livre), que destacou a trajet\u00f3ria da tecnologia desenvolvida em Abu Dhabi, desde os laborat\u00f3rios dos Emirados \u00c1rabes Unidos at\u00e9 sua implanta\u00e7\u00e3o internacional. O evento tamb\u00e9m refor\u00e7ou o papel cada vez mais importante do pa\u00eds como produtor de tecnologias avan\u00e7adas adotadas globalmente.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><b>Fonte:<\/b><a rel=\"follow\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Faetoswire.com%2Fen%2Fnews%2Ftii04052026e&amp;esheet=54526651&amp;newsitemid=20260504281129&amp;lan=pt-BR&amp;anchor=AETOSWire&amp;index=1&amp;md5=2c6c636c0ec315a51086b1bb2f5cefca\" shape=\"rect\" target=\"_blank\"><b>AETOSWire<\/b><\/a><\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\">\nO texto no idioma original deste an\u00fancio \u00e9 a vers\u00e3o oficial autorizada. As tradu\u00e7\u00f5es s\u00e3o fornecidas apenas como uma facilidade e devem se referir ao texto no idioma original, que \u00e9 a \u00fanica vers\u00e3o do texto que tem efeito legal.<\/p>\n<p xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/cts.businesswire.com\/ct\/CT?id=bwnews&amp;sty=20260504281129r1&amp;sid=brdno&amp;distro=ftp\"><span class=\"bwct31415\"><\/span><\/p>\n<p id=\"mmgallerylink\" xmlns=\"http:\/\/www.w3.org\/1999\/xhtml\"><span id=\"mmgallerylink-phrase\">Ver a vers\u00e3o original em businesswire.com: <\/span><span id=\"mmgallerylink-link\"><a href=\"https:\/\/www.businesswire.com\/news\/home\/20260504281129\/pt\/\" rel=\"follow\" target=\"_blank\">https:\/\/www.businesswire.com\/news\/home\/20260504281129\/pt\/<\/a><\/span><\/p>\n<p>Videos:<br \/><a href='https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2793265\/19\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_AI_Technology_-_Video_-_AETOSWire.mp4' target='_blank' >https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2793265\/19\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_AI_Technology_-_Video_-_AETOSWire.mp4<\/a><br \/><b>Contato:<\/b><\/p>\n<p><a rel=\"follow\" href=\"mailto:tii@edelman.com\" shape=\"rect\">tii@edelman.com<br \/>\n<\/a><\/p>\n<\/p>\n<p>Para a Opaque\n<\/p>\n<p><a rel=\"follow\" href=\"mailto:opaquesystems@inkhouse.com\" shape=\"rect\">opaquesystems@inkhouse.com<br \/>\n<\/a><\/p>\n<\/p>\n<p>Jennifer Dewan\n<\/p>\n<p><a rel=\"follow\" href=\"mailto:Jennifer.dewan@tii.ae\" shape=\"rect\">Jennifer.dewan@tii.ae<\/a><\/p>\n<p><strong>Fonte: <\/strong><a href='http:\/\/www.businesswire.com\/portal\/site\/home\/' target='_blank'>BUSINESS WIRE<\/a><img src='https:\/\/api.dino.com.br\/v2\/news\/tr\/330897?partnerId=4593' alt=\"\" style=\"border:0px;width:1px;height:1px;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Novos recursos possibilitam a implanta\u00e7\u00e3o segura de agentes de IA em dados sens\u00edveis e regulamentados, com regras verific\u00e1veis, refor\u00e7adas por hardware e com garantias criptogr\u00e1ficas projetadas para resistir \u00e0 computa\u00e7\u00e3o qu\u00e2ntica<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[315],"tags":[349,337,324,351,323],"class_list":["post-21330","post","type-post","status-publish","format-standard","category-noticias-corporativas-dino","tag-arte","tag-entretenimento","tag-negocios","tag-sociedade","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/angelboss.com.br\/en\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"og:description\" content=\"Novos recursos possibilitam a implanta\u00e7\u00e3o segura de agentes de IA em dados sens\u00edveis e regulamentados, com regras verific\u00e1veis, refor\u00e7adas por hardware e com garantias criptogr\u00e1ficas projetadas para resistir \u00e0 computa\u00e7\u00e3o qu\u00e2ntica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/angelboss.com.br\/en\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-04T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2791846\/4\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg\" \/>\n<meta name=\"author\" content=\"DINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/\"},\"author\":{\"name\":\"DINO\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\"},\"headline\":\"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica\",\"datePublished\":\"2026-05-04T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/\"},\"wordCount\":1584,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mms.businesswire.com\\\/media\\\/20260504281129\\\/pt\\\/2791846\\\/4\\\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg\",\"keywords\":[\"ARTE\",\"ENTRETENIMENTO\",\"NEG\u00d3CIOS\",\"SOCIEDADE\",\"TECNOLOGIA\"],\"articleSection\":[\"Not\u00edcias Corporativas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/\",\"name\":\"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mms.businesswire.com\\\/media\\\/20260504281129\\\/pt\\\/2791846\\\/4\\\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg\",\"datePublished\":\"2026-05-04T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mms.businesswire.com\\\/media\\\/20260504281129\\\/pt\\\/2791846\\\/4\\\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg\",\"contentUrl\":\"https:\\\/\\\/mms.businesswire.com\\\/media\\\/20260504281129\\\/pt\\\/2791846\\\/4\\\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/2026\\\/05\\\/04\\\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/angelboss.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss\",\"description\":\"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil\",\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"alternateName\":\"Maior Portal e Blog de Beleza Masculina e Luxo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angelboss.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"width\":1280,\"height\":1280,\"caption\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\",\"name\":\"DINO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"caption\":\"DINO\"},\"url\":\"http:\\\/\\\/angelboss.com.br\\\/en\\\/author\\\/DINO\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/angelboss.com.br\/en\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/","og_locale":"en_US","og_type":"article","og_title":"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","og_description":"Novos recursos possibilitam a implanta\u00e7\u00e3o segura de agentes de IA em dados sens\u00edveis e regulamentados, com regras verific\u00e1veis, refor\u00e7adas por hardware e com garantias criptogr\u00e1ficas projetadas para resistir \u00e0 computa\u00e7\u00e3o qu\u00e2ntica","og_url":"https:\/\/angelboss.com.br\/en\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/","og_site_name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","article_published_time":"2026-05-04T00:00:00+00:00","og_image":[{"url":"https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2791846\/4\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg","type":"","width":"","height":""}],"author":"DINO","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DINO","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/#article","isPartOf":{"@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/"},"author":{"name":"DINO","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5"},"headline":"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica","datePublished":"2026-05-04T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/"},"wordCount":1584,"commentCount":0,"publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"image":{"@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/#primaryimage"},"thumbnailUrl":"https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2791846\/4\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg","keywords":["ARTE","ENTRETENIMENTO","NEG\u00d3CIOS","SOCIEDADE","TECNOLOGIA"],"articleSection":["Not\u00edcias Corporativas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/","url":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/","name":"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","isPartOf":{"@id":"https:\/\/angelboss.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/#primaryimage"},"image":{"@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/#primaryimage"},"thumbnailUrl":"https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2791846\/4\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg","datePublished":"2026-05-04T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/#primaryimage","url":"https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2791846\/4\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg","contentUrl":"https:\/\/mms.businesswire.com\/media\/20260504281129\/pt\/2791846\/4\/OPAQUE_Acquires_Abu_Dhabi-Developed_Cryptographic_Photo_-_AETOSWire.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/angelboss.com.br\/2026\/05\/04\/330897-opaque-adquire-tecnologia-de-ia-criptografica-desenvolvida-em-abu-dhabi-da-tii-ampliando-a-ia-confidencial-para-todo-o-ciclo-de-vida-com-protecao-pos-quantica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/angelboss.com.br\/"},{"@type":"ListItem","position":2,"name":"OPAQUE adquire tecnologia de IA criptogr\u00e1fica desenvolvida em Abu Dhabi da TII, ampliando a IA confidencial para todo o ciclo de vida com prote\u00e7\u00e3o p\u00f3s-qu\u00e2ntica"}]},{"@type":"WebSite","@id":"https:\/\/angelboss.com.br\/#website","url":"https:\/\/angelboss.com.br\/","name":"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss","description":"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil","publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"alternateName":"Maior Portal e Blog de Beleza Masculina e Luxo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angelboss.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/angelboss.com.br\/#organization","name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","url":"https:\/\/angelboss.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","contentUrl":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","width":1280,"height":1280,"caption":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss"},"image":{"@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5","name":"DINO","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","caption":"DINO"},"url":"http:\/\/angelboss.com.br\/en\/author\/DINO\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/21330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/comments?post=21330"}],"version-history":[{"count":0,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/21330\/revisions"}],"wp:attachment":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/media?parent=21330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/categories?post=21330"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/tags?post=21330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}