{"id":20587,"date":"2026-04-28T00:00:00","date_gmt":"2026-04-28T00:00:00","guid":{"rendered":"https:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/"},"modified":"2026-04-28T00:00:00","modified_gmt":"2026-04-28T00:00:00","slug":"330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia","status":"publish","type":"post","link":"http:\/\/angelboss.com.br\/en\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/","title":{"rendered":"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia"},"content":{"rendered":"<p>ZURIQUE, April 28, 2026 (GLOBE NEWSWIRE) &#8212; <strong>Crian\u00e7as em risco de anafilaxia ainda n\u00e3o est\u00e3o protegidas de forma consistente nas escolas<\/strong>, apesar de orienta\u00e7\u00f5es m\u00e9dicas claras.<\/p>\n<p>Esse foi o alerta feito no Congresso dos Deputados da Espanha durante o evento <em>&quot;Cada minuto conta: escolas seguras contra a anafilaxia&quot;<\/em> onde a Associa\u00e7\u00e3o Espanhola de Pessoas com Alergias Alimentares e a L\u00e1tex (AEPNAA), a Sociedade Espanhola de Alergologia e Imunologia Cl\u00ednica (SEAIC), a Sociedade Espanhola de Imunologia Cl\u00ednica Pedi\u00e1trica, Alergologia e Asma (SEICAP) e a European Academy of Allergy and Clinical Immunology (EAACI) <strong>endossaram um manifesto conjunto pedindo salvaguardas mais fortes em ambientes escolares<\/strong>.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ml-eu.globenewswire.com\/Resource\/Download\/28fd2af7-c688-492e-a5c0-bdb566bfec27\/image1.jpeg\" alt=\"\" data-description=\"\" data-source=\"\" \/><\/p>\n<p>Representando a EAACI, a Presidente Mar\u00eda Jos\u00e9 Torres disse que a resposta &agrave; anafilaxia permanece inconsistente, <strong>com a seguran\u00e7a das crian\u00e7as dependente do acaso<\/strong> &#8212; de se a equipe reconhece os sintomas, se a medica\u00e7\u00e3o \u00e9 acess\u00edvel e se os protocolos existem.<\/p>\n<p>A anafilaxia \u00e9 uma rea\u00e7\u00e3o al\u00e9rgica grave e r\u00e1pida que pode se tornar fatal em poucos minutos. Para muitas fam\u00edlias, esse risco faz parte da vida cotidiana &#8211; especialmente durante o hor\u00e1rio escolar, quando as crian\u00e7as est\u00e3o fora do alcance imediato dos pais ou cuidadores.<\/p>\n<p>O manifesto estabelece medidas pr\u00e1ticas para preencher essas lacunas: <strong>um protocolo comum para as escolas, treinamento obrigat\u00f3rio da equipe, autoinjetores de adrenalina acess\u00edveis, planos de cuidados individualizados e uma coordena\u00e7\u00e3o mais forte entre os sistemas de sa\u00fade e educa\u00e7\u00e3o<\/strong>.<\/p>\n<p><strong>&quot;Para muitas crian\u00e7as, a anafilaxia n\u00e3o \u00e9 um risco hipot\u00e9tico &#8211; faz parte da vida di\u00e1ria&quot;<\/strong>, disse Mar\u00eda Jos\u00e9 Torres, Presidente da EAACI. <strong>&quot;Diante uma rea\u00e7\u00e3o grave a resposta deve ser imediata. N\u00e3o pode haver atrasos ou incertezas sobre quem deve agir.&quot;<\/strong><\/p>\n<p>Ela acrescentou que n\u00edveis desiguais de prote\u00e7\u00e3o nas escolas s\u00e3o inaceit\u00e1veis. <strong>&quot;As crian\u00e7as n\u00e3o devem estar mais seguras em uma escola do que em outra. Precisamos de protocolos claros, equipe treinada e acesso imediato a tratamento de emerg\u00eancia &#8211; antes que o tempo seja perdido.&quot;<\/strong><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ml-eu.globenewswire.com\/Resource\/Download\/1033b1cd-09c0-4626-ab27-cbc72e2bbd6c\/image2.jpeg\" alt=\"\" data-description=\"\" data-source=\"\" \/><\/p>\n<p>O evento reuniu organiza\u00e7\u00f5es de pacientes, sociedades cient\u00edficas, profissionais de sa\u00fade, fam\u00edlias e institui\u00e7\u00f5es p\u00fablicas, <strong>destacando a incerteza di\u00e1ria enfrentada pelas fam\u00edlias<\/strong> que n\u00e3o sabem se as escolas est\u00e3o preparadas para responder.<\/p>\n<p>Para a EAACI, isso \u00e9 muito claro. <strong>A prioridade agora \u00e9 a implementa\u00e7\u00e3o<\/strong> &#8212; garantir que as crian\u00e7as em risco sejam protegidas na pr\u00e1tica, n\u00e3o apenas no papel.<\/p>\n<p>Ao apoiar esta iniciativa, a EAACI reafirma o seu compromisso de promover medidas baseadas em evid\u00eancias que aumentem a seguran\u00e7a do paciente e protejam as crian\u00e7as e as fam\u00edlias onde mais precisarem.<\/p>\n<p><strong>Sobre a EAACI<\/strong><\/p>\n<p>A European Academy of Allergy and Clinical Immunology (EAACI) \u00e9 a principal organiza\u00e7\u00e3o profissional da Europa no campo da alergia e imunologia cl\u00ednica. A EAACI conta com m\u00e9dicos, pesquisadores e profissionais de sa\u00fade aliados para melhorar a sa\u00fade e o atendimento das pessoas afetadas pelas doen\u00e7as al\u00e9rgicas e imunol\u00f3gicas, por meio da pesquisa, educa\u00e7\u00e3o e advocacia.<\/p>\n<p>Contato: communications@eaaci.org | +41 44 205 55 33<\/p>\n<p>Fotos deste comunicado podem ser encontradas em:<\/p>\n<p><a href=\"https:\/\/www.globenewswire.com\/Tracker?data=cHoLsZSCr_Xc2x0MTkTlqzweiSRa92FefkyAWE1qesf-3zl5W9hcuCeMKdVbLnitJaxvibAKAajlj3jiVgHO2C9efkEOOBWAGuwUQIi-ym0aCG3LiFCdQ5IEhK_aVnQW8cXQcop5QXkPqq1wpkyx9_oQn_ynxLJj_fWr_77esKW-rbu_3WKTjxfGLGn41OVf21bOdq5vDL0l_Fgf2c1nT1XSKAmCzh13zwF4aAEn5RVpF9vxD4kzvpReQhcPupBkBaJyhjskCFcYxCpFciEZ-g==\" rel=\"follow\" target=\"_blank\">http:\/\/www.globenewswire.com\/NewsRoom\/AttachmentNg\/ca605fbb-0ff4-40ba-be81-fbfc0b45538c<\/a><\/p>\n<p><a href=\"https:\/\/www.globenewswire.com\/Tracker?data=cHoLsZSCr_Xc2x0MTkTlqzweiSRa92FefkyAWE1qesf-3zl5W9hcuCeMKdVbLnitJaxvibAKAajlj3jiVgHO2PoMbUyjVnSL2gt9MtxwsYz1-c26Na2yqMT9YmGWEVL0zqgslhH5rqOolyls58nwEI-yt9SVUD2iyKvgTxr_vBKh-Krf2VhsPkm6KjxGR1-vEFakjNvNff7lnPj047iTEaifwIosuAqFuX1nDKTBwM15f_h7g-KOZ_8QnDX8-DmhkXRHkkfcVWMgg0p7q5k-rQ==\" rel=\"follow\" target=\"_blank\">http:\/\/www.globenewswire.com\/NewsRoom\/AttachmentNg\/e7eba67f-15f6-4f73-85ae-503e18d6036a<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.globenewswire.com\/newsroom\/ti?nf=MTAwMTE3ODU5MSM0MDIzODA2NTQjMjI2MTMzNw==\" alt=\"\" data-description=\"\" data-source=\"\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/ml-eu.globenewswire.com\/media\/MDA2NDViMGMtNmQyZC00NDZmLThiMmQtZGM1ZGVlN2JiZTY3LTEyNzI4ODctMjAyNi0wNC0yOC1wdA==\/tiny\/European-Academy-of-Allergy-an.png\" alt=\"\" data-description=\"\" data-source=\"\" \/><\/p>\n<p><a href=\"https:\/\/www.globenewswire.com\/NewsRoom\/AttachmentNg\/f4b92ae8-0022-43fa-b8a3-bbe4246a45cd\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/ml-eu.globenewswire.com\/media\/f4b92ae8-0022-43fa-b8a3-bbe4246a45cd\/small\/eaaci-logo-png.png\" border=\"0\" width=\"150\" height=\"34\" alt=\"Primary Logo\" \/><\/a><\/p>\n<p>GLOBENEWSWIRE (Distribution ID 1001178591)<\/p>\n<p><img src='https:\/\/api.dino.com.br\/v2\/news\/tr\/330639?partnerId=4593' alt=\"\" style=\"border:0px;width:1px;height:1px;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>No Congresso dos Deputados da Espanha, a presidente da EAACI, Mar\u00eda Jos\u00e9 Torres, apoiou um manifesto conjunto com a AEPNAA, a SEAIC e a SEICAP, solicitando medidas urgentes em rela\u00e7\u00e3o aos protocolos escolares, \u00e0 capacita\u00e7\u00e3o de profissionais e ao acesso \u00e0 adrenalina \u2014 um recurso vital<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[315],"tags":[337,357,323],"class_list":["post-20587","post","type-post","status-publish","format-standard","category-noticias-corporativas-dino","tag-entretenimento","tag-estilo-de-vida","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/angelboss.com.br\/en\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"og:description\" content=\"No Congresso dos Deputados da Espanha, a presidente da EAACI, Mar\u00eda Jos\u00e9 Torres, apoiou um manifesto conjunto com a AEPNAA, a SEAIC e a SEICAP, solicitando medidas urgentes em rela\u00e7\u00e3o aos protocolos escolares, \u00e0 capacita\u00e7\u00e3o de profissionais e ao acesso \u00e0 adrenalina \u2014 um recurso vital\" \/>\n<meta property=\"og:url\" content=\"http:\/\/angelboss.com.br\/en\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-28T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ml-eu.globenewswire.com\/Resource\/Download\/28fd2af7-c688-492e-a5c0-bdb566bfec27\/image1.jpeg\" \/>\n<meta name=\"author\" content=\"DINO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"DINO\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/\"},\"author\":{\"name\":\"DINO\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\"},\"headline\":\"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia\",\"datePublished\":\"2026-04-28T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ml-eu.globenewswire.com\\\/Resource\\\/Download\\\/28fd2af7-c688-492e-a5c0-bdb566bfec27\\\/image1.jpeg\",\"keywords\":[\"ENTRETENIMENTO\",\"ESTILO DE VIDA\",\"TECNOLOGIA\"],\"articleSection\":[\"Not\u00edcias Corporativas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/\",\"url\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/\",\"name\":\"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ml-eu.globenewswire.com\\\/Resource\\\/Download\\\/28fd2af7-c688-492e-a5c0-bdb566bfec27\\\/image1.jpeg\",\"datePublished\":\"2026-04-28T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ml-eu.globenewswire.com\\\/Resource\\\/Download\\\/28fd2af7-c688-492e-a5c0-bdb566bfec27\\\/image1.jpeg\",\"contentUrl\":\"https:\\\/\\\/ml-eu.globenewswire.com\\\/Resource\\\/Download\\\/28fd2af7-c688-492e-a5c0-bdb566bfec27\\\/image1.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/angelboss.com.br\\\/2026\\\/04\\\/28\\\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"http:\\\/\\\/angelboss.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#website\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss\",\"description\":\"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil\",\"publisher\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\"},\"alternateName\":\"Maior Portal e Blog de Beleza Masculina e Luxo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/angelboss.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#organization\",\"name\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"contentUrl\":\"https:\\\/\\\/angelboss.com.br\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg\",\"width\":1280,\"height\":1280,\"caption\":\"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss\"},\"image\":{\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/angelboss.com.br\\\/#\\\/schema\\\/person\\\/b6676b8d991f97199ef2d5b8e5c2d8a5\",\"name\":\"DINO\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g\",\"caption\":\"DINO\"},\"url\":\"http:\\\/\\\/angelboss.com.br\\\/en\\\/author\\\/DINO\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/angelboss.com.br\/en\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/","og_locale":"en_US","og_type":"article","og_title":"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","og_description":"No Congresso dos Deputados da Espanha, a presidente da EAACI, Mar\u00eda Jos\u00e9 Torres, apoiou um manifesto conjunto com a AEPNAA, a SEAIC e a SEICAP, solicitando medidas urgentes em rela\u00e7\u00e3o aos protocolos escolares, \u00e0 capacita\u00e7\u00e3o de profissionais e ao acesso \u00e0 adrenalina \u2014 um recurso vital","og_url":"http:\/\/angelboss.com.br\/en\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/","og_site_name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","article_published_time":"2026-04-28T00:00:00+00:00","og_image":[{"url":"https:\/\/ml-eu.globenewswire.com\/Resource\/Download\/28fd2af7-c688-492e-a5c0-bdb566bfec27\/image1.jpeg","type":"","width":"","height":""}],"author":"DINO","twitter_card":"summary_large_image","twitter_misc":{"Written by":"DINO","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/#article","isPartOf":{"@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/"},"author":{"name":"DINO","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5"},"headline":"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia","datePublished":"2026-04-28T00:00:00+00:00","mainEntityOfPage":{"@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"image":{"@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/#primaryimage"},"thumbnailUrl":"https:\/\/ml-eu.globenewswire.com\/Resource\/Download\/28fd2af7-c688-492e-a5c0-bdb566bfec27\/image1.jpeg","keywords":["ENTRETENIMENTO","ESTILO DE VIDA","TECNOLOGIA"],"articleSection":["Not\u00edcias Corporativas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/","url":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/","name":"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia - Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","isPartOf":{"@id":"https:\/\/angelboss.com.br\/#website"},"primaryImageOfPage":{"@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/#primaryimage"},"image":{"@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/#primaryimage"},"thumbnailUrl":"https:\/\/ml-eu.globenewswire.com\/Resource\/Download\/28fd2af7-c688-492e-a5c0-bdb566bfec27\/image1.jpeg","datePublished":"2026-04-28T00:00:00+00:00","breadcrumb":{"@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/#primaryimage","url":"https:\/\/ml-eu.globenewswire.com\/Resource\/Download\/28fd2af7-c688-492e-a5c0-bdb566bfec27\/image1.jpeg","contentUrl":"https:\/\/ml-eu.globenewswire.com\/Resource\/Download\/28fd2af7-c688-492e-a5c0-bdb566bfec27\/image1.jpeg"},{"@type":"BreadcrumbList","@id":"http:\/\/angelboss.com.br\/2026\/04\/28\/330639-cada-minuto-conta-eaaci-pede-acao-urgente-para-tornar-as-escolas-seguras-para-criancas-em-risco-de-anafilaxia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"http:\/\/angelboss.com.br\/"},{"@type":"ListItem","position":2,"name":"Cada minuto conta: EAACI pede a\u00e7\u00e3o urgente para tornar as escolas seguras para crian\u00e7as em risco de anafilaxia"}]},{"@type":"WebSite","@id":"https:\/\/angelboss.com.br\/#website","url":"https:\/\/angelboss.com.br\/","name":"Portal Masculino de Moda, Beleza, Luxo e Business - Angel Boss","description":"O Maior Portal sobre Moda, Luxo, Beleza e Business Masculino do Brasil","publisher":{"@id":"https:\/\/angelboss.com.br\/#organization"},"alternateName":"Maior Portal e Blog de Beleza Masculina e Luxo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/angelboss.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/angelboss.com.br\/#organization","name":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss","url":"https:\/\/angelboss.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","contentUrl":"https:\/\/angelboss.com.br\/wp-content\/uploads\/2025\/12\/WhatsApp-Image-2025-12-11-at-12.54.26.jpeg","width":1280,"height":1280,"caption":"Portal Masculino de Moda, Beleza, Luxo and Business - Angel Boss"},"image":{"@id":"https:\/\/angelboss.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/angelboss.com.br\/#\/schema\/person\/b6676b8d991f97199ef2d5b8e5c2d8a5","name":"DINO","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f29568383aedf96da155b6f87103b0e04b1c662f982055cda25086444ab33ff8?s=96&d=mm&r=g","caption":"DINO"},"url":"http:\/\/angelboss.com.br\/en\/author\/DINO\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/20587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/comments?post=20587"}],"version-history":[{"count":0,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/posts\/20587\/revisions"}],"wp:attachment":[{"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/media?parent=20587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/categories?post=20587"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/angelboss.com.br\/en\/wp-json\/wp\/v2\/tags?post=20587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}